{"id":8567,"date":"2018-03-27T11:05:22","date_gmt":"2018-03-27T10:05:22","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?page_id=8567"},"modified":"2026-07-08T13:05:34","modified_gmt":"2026-07-08T12:05:34","slug":"matriculacion","status":"publish","type":"page","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/","title":{"rendered":"matriculaci\u00f3n"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbADMISI\u00d3N\u00bb subhead=\u00bbAdmisi\u00f3n 2025\/2026&#8243; title_font_color=\u00bb#ffffff\u00bb module_class=\u00bbpagina-imagen-cabecera\u00bb _builder_version=\u00bb4.27.4&#8243; title_text_color=\u00bb#ffffff\u00bb title_font_size=\u00bb40px\u00bb background_color=\u00bbrgba(255, 255, 255, 0)\u00bb background_image=\u00bbhttps:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/04\/IMG_4653.png\u00bb background_size=\u00bbcustom\u00bb background_image_width=\u00bb100%\u00bb background_image_height=\u00bb0%\u00bb background_position=\u00bbtop_center\u00bb background_vertical_offset=\u00bb33%\u00bb max_width_tablet=\u00bb50px\u00bb background_url=\u00bbhttps:\/\/alicante.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2017\/04\/Captura-de-pantalla-2017-04-13-a-las-16.14.37.png\u00bb global_colors_info=\u00bb{}\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbpagina-seccion-contenido\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0%|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb3_4,1_4&#8243; module_class=\u00bbpagina-texto\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb25px|||\u00bb custom_padding=\u00bb25px|0px|0px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto matr\u00edcula\u00bb _builder_version=\u00bb4.27.5&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<blockquote>\n<h1>Admisi\u00f3n y Matriculaci\u00f3n 2026-2027<\/h1>\n<p>Documentos<\/p>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div><span style=\"color: #000000; font-size: large;\">Datos del colegio:<\/span><\/div>\n<div><span style=\"color: #ff0000; font-size: large;\">(VALENCIA) &#8211; COLEGIO SALESIANOS SAN JUAN BOSCO con c\u00f3digo de centro 46013116<\/span><\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<p>[\/et_pb_text][et_pb_accordion disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bbResoluci\u00f3n admisi\u00f3n\u00bb open=\u00bbon\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><b>RESOLUCI\u00d3N de 25 de febrero de 2026, de la Direcci\u00f3n General de Centros Docentes, por la que se establece el calendario y se dictan instrucciones respecto al procedimiento de admisi\u00f3n del alumnado en los centros docentes sostenidos con fondos p\u00fablicos de la Comunitat Valenciana que imparten ense\u00f1anzas de Educaci\u00f3n Infantil, Educaci\u00f3n Primaria, Educaci\u00f3n Secundaria Obligatoria y Bachillerato, y en los centro<\/b><\/p>\n<p><b><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/04\/Resolucion_admision_2026_2027.pdf\" rel=\"attachment wp-att-24386\">R<\/a><\/b><b><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/04\/Resolucion_admision_2026_2027.pdf\" rel=\"attachment wp-att-24386\">esoluci\u00f3n_admisi\u00f3n_2026_2027<\/a>s de Educaci\u00f3n Especial, para el curso 2026-2027.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCriterios valoraci\u00f3n de solicitudes\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p>Criterios valoraci\u00f3n de las solicitudes<\/p>\n<p><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/04\/Anexo-X_Criterios-para-la-valoracion-de-las-solicitudes.pdf\" rel=\"attachment wp-att-24385\">Anexo X_Criterios para la valoraci\u00f3n de las solicitudes<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCalendario de Admisi\u00f3n\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/04\/Anexo-VII_Cuadro-calendario-admision-alumnado-Educacion-Infantil-Primaria-ESO-y-Bachillerato_FASE-ORDINARIA.pdf\" rel=\"attachment wp-att-24384\">Anexo VII_Cuadro calendario admisi\u00f3n alumnado Educaci\u00f3n Infantil, Primaria, ESO y Bachillerato_FASE ORDINARIA<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbSorteo de letras de desempate\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/04\/Acta-sorteo-letras-prioridad.pdf\" rel=\"attachment wp-att-24383\">Acta sorteo letras prioridad<\/a><\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][et_pb_accordion disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.24.0&#8243; _module_preset=\u00bbdefault\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bbCALENDARIO DE ADMISI\u00d3N\u00bb open=\u00bbon\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Quien desee realizar la solicitud en el colegio, dispondr\u00e1 de ordenadores y asistencia previa cita en el siguiente enlace (disponible en breve)<\/p>\n<p><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/03\/CALENDARIO-23-24-admision.pdf\" rel=\"attachment wp-att-18972\">CALENDARIO ADMISI\u00d3N 23-24 <\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCRITERIOS DE PUNTUACI\u00d3N\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<table style=\"height: 1519px; border-style: solid; width: 628px; border-color: #000000;\" width=\"926\">\n<tbody>\n<tr style=\"height: 28px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 28px;\"><strong>\u00a0<\/strong><\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 28px;\"><strong>Criterio<\/strong><\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 28px;\"><strong>Puntos<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 148px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 148px;\">1<\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 148px;\">\n<p><strong>Hermanos o hermanas:<\/strong><\/p>\n<p>Por cada hermano o hermana matriculado en el centro solicitado, que haya de continuar asistiendo al mismo curso escolar para el que se solicita plaza<\/p>\n<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 148px;\"><strong>1<\/strong><strong>5<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 148px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 148px;\">2<\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 148px;\">\n<p><strong>Padres, madres, tutores trabajadores centro\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>Cuando uno o ambos padres, madres o tutores sean trabajadores, en activo, en el centro:<\/p>\n<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 148px;\"><strong>5<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 88px;\" rowspan=\"3\">3<\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 28px;\"><strong>Domicilio:<\/strong><\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 28px;\"><strong>\u00a0<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 30px;\">\n<td style=\"width: 523.016px; border-color: #000000; height: 30px; border-style: solid;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00c1rea de influencia<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 30px;\"><strong>10<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 30px;\">\n<td style=\"width: 523.016px; border-color: #000000; height: 30px; border-style: solid;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00c1rea lim\u00edtrofe<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 30px;\"><strong>5<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 121px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 121px;\">4<\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 121px;\">\n<p><strong>Renta Valenciana de Inclusi\u00f3n:<\/strong><\/p>\n<p>En caso de las personas destinatarias de la Renta Valenciana de Inclusi\u00f3n (RVI)<\/p>\n<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 121px;\">\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>4<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 241px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 538px;\" rowspan=\"4\">5<\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 241px;\">\n<p><strong>Renta Familiar<\/strong><\/p>\n<p>Sin ser persona beneficiaria de la RVI<\/p>\n<p>De acuerdo con el <strong>IPREM<\/strong> (<strong>7908,60\u20ac), <\/strong>correspondiente a 14 pagas, en relaci\u00f3n al ejercicio fiscal anterior en 2 a\u00f1os al a\u00f1o natural en que se solicita plaza:<\/p>\n<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 241px;\">\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 28px;\">Renta anual per c\u00e1pita igual o inferior a la mitad del IPREM<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 28px;\"><strong>3,5<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 28px;\">Renta anual per c\u00e1pita superior a la mitad del IPREM e inferior o igual al IPREM<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 28px;\"><strong>3<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 241px;\">\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 241px;\">\n<p>Renta anual per c\u00e1pita superior al IPREM e inferior o igual al resultado de multiplicar el IPREM por 1\u00b45<\/p>\n<p>Renta anual per c\u00e1pita superior al resultado de multiplicar el IPREM por 1\u00b45 e inferior o igual al resultado de multiplicar el IPREM por 2<\/p>\n<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 241px;\">\n<p><strong>2,5<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>2<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 28px;\" rowspan=\"3\">6<\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 28px;\"><strong>Familia numerosa:<\/strong><\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 28px;\"><strong>\u00a0<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 28px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Especial<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 28px;\"><strong>5<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 28px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 General<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 28px;\"><strong>3<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 181px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 181px;\" rowspan=\"2\">7<\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 181px;\">\n<p><strong>Discapacidad del alumno o alumna<\/strong><\/p>\n<p>Igual o superior al 65%<\/p>\n<p>Igual o superior al 33% e inferior o igual al 64%<\/p>\n<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 181px;\">\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>7<\/strong><\/p>\n<p><strong>4<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 10px;\">\n<p><strong>Discapacidad de los padres, madres, tutores, hermanos o hermanas del alumno o alumna<\/strong><\/p>\n<p>Igual o superior al 65%<\/p>\n<p>Igual o superior al 33% e inferior o igual al 64%<\/p>\n<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 10px;\">\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>5<\/strong><\/p>\n<p><strong>3<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 52px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 52px;\">8<\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 52px;\">\n<p><strong>Familia monoparental:<\/strong><\/p>\n<p>Especial<\/p>\n<p>General<\/p>\n<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 52px;\">\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>5<\/strong><\/p>\n<p><strong>3<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 121px;\">\n<td style=\"width: 19.25px; border-style: solid; border-color: #000000; height: 121px;\">9<\/td>\n<td style=\"width: 521.016px; border-style: solid; border-color: #000000; height: 121px;\">\n<p><strong>Acceso a Bachillerato:<\/strong><\/p>\n<p>Se agregar\u00e1 la nota media obtenida en ESO o en un ciclo formativo de grado medio<\/p>\n<\/td>\n<td style=\"width: 65.7344px; border-style: solid; border-color: #000000; text-align: center; height: 121px;\"><strong>\u00a0<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Actualizado 14 de marzo de 2023<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bb\u00c1REAS DE INFLUENCIA\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p>Pendiente de publicar zonificaci\u00f3n curso 2023-24<\/p>\n<p><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/04\/Res_Zonificacio_Valencia_ciutat_2022.pdf\" rel=\"attachment wp-att-16983\">RESOLUCI\u00d3N ZONIFICACI\u00d3N_Valencia Ciudad_2022<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCRITERIOS Y SORTEO LETRAS DESEMPATE\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p>Los empates que, en su caso se produzcan, se dirimir\u00e1n aplicando sucesivamente la mayor puntuaci\u00f3n obtenida en los criterios siguientes y en el orden establecido hasta el momento en que se produzca el desempate<\/p>\n<p>Los empates que, si es el caso, se produzcan se dirimir\u00e1n aplicando sucesivamente la mayor puntuaci\u00f3n obtenida en los criterios siguientes:<br \/>1. Existencia de hermanos o hermanas, u otra persona que se encuentre en situaci\u00f3n de acogida familiar o en guarda con fines de adopci\u00f3n, matriculados en el centro.<br \/>2. Padre, madre o tutores legales trabajadores del centro docente.<br \/>3. Proximidad del domicilio donde resida el alumno o alumna o del puesto de trabajo de alguno de sus padres, madres o tutores legales.<br \/>4. Condici\u00f3n de persona destinataria de la renta valenciana de inclusi\u00f3n.<br \/>5. Renta per c\u00e1pita de la unidad familiar.<br \/>6. Condici\u00f3n legal de familia numerosa.<br \/>7. Concurrencia de discapacidad en el alumnado, en sus padres, madres, tutores legales, hermanos o hermanas.<br \/>8. Familia monoparental.<br \/>9. Expediente acad\u00e9mico, solo en ense\u00f1anzas post obligatorias.<br \/>10. En las situaciones de empate que se produzcan despu\u00e9s de aplicar estos criterios, la ordenaci\u00f3n de las solicitudes afectadas se har\u00e1 por sorteo p\u00fablico, de acuerdo con el procedimiento que establezca la conselleria competente en materia de educaci\u00f3n.\u00bb<\/p>\n<div>\u00a0<span style=\"color: #000000;\" data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">\u201cSeg\u00fan lo establecido en el apartado 3 del art\u00edculo 38 del Decreto 40\/2016, en las situaciones de empate que se produzcan despu\u00e9s de aplicar los criterios de desempates, el sorteo p\u00fablico se realizar\u00e1 de acuerdo con el procedimiento siguiente: se elegir\u00e1n dos letras por las cuales se ordenar\u00e1 el primer apellido; tambi\u00e9n otras dos letras por las cuales se ordenar\u00e1 el segundo apellido, y que se aplicar\u00e1n cuando exista coincidencia con el primero. En caso de no disponer de un segundo apellido, se considerar\u00e1 que este empieza con \u2018AA\u2019.<\/span><\/div>\n<div data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\"><span style=\"color: #000000;\" data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Para el presente curso escolar 2023-2024, para ordenar el primer apellido las letras son <b data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">SP<\/b> (en este orden) y para ordenar el segundo apellido cuando exista coincidencia con el primero las letras <b data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">PS<\/b> (en este orden).\u00bb<\/span><\/div>\n<div data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Actualizado 2 de marzo de 2023<\/div>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbSOLICITUD DE ADMISI\u00d3N\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><span style=\"font-family: arial, sans-serif;\">Para realizar la solicitud telem\u00e1tica de admisi\u00f3n deber\u00e1n acceder al enlace que encontrar\u00e1 al final del p\u00e1rrafo.<\/span><\/p>\n<p><span style=\"font-family: arial, sans-serif;\">El\u00a0<b>tr\u00e1mite de solicitud de plaza para el curso 23-24 ser\u00e1 exclusivamente telem\u00e1tico<\/b>\u00a0y con el fin de poder dar asistencia a las\u00a0familias que deseen elegir\u00a0nuestro centro educativo como primera opci\u00f3n, el colegio pone a su disposici\u00f3n ordenadores y personal de secretar\u00eda para realizar el tr\u00e1mite en nuestras\u00a0instalaciones y ayudarles ante cualquier duda que les pueda surgir durante el mismo.\u00a0<\/span><\/p>\n<div><span style=\"font-family: arial, sans-serif;\">Para poder atenderles de la manera que merecen, ser\u00e1 necesario acudir con cita, por lo que les adjuntamos un enlace al formulario de cita previa para que puedan reservar el d\u00eda y hora seg\u00fan su disponibilidad:<\/span><\/div>\n<div><span style=\"font-family: arial, sans-serif;\">\u00a0<\/span><\/div>\n<div><span style=\"font-family: arial, sans-serif;\">-RESERVA CITA PREVIA ETAPAS INF\/PRIM (del 20\/04 al 28\/04). <span style=\"color: #ff0000;\">Pr\u00f3ximamente se habilitar\u00e1 enlace.<\/span><\/span><\/div>\n<div><span style=\"font-family: arial, sans-serif;\">-RESERVA CITA PREVIA ESO y BACHILLERATO (DEL 04\/05 AL 12\/05). <span style=\"color: #ff0000;\">Pr\u00f3ximamente de habilitar\u00e1 enlace.<\/span><\/span><\/div>\n<p><span style=\"font-family: arial, sans-serif;\">Recuerde que solamente deber\u00e1 hacer una solicitud eligiendo hasta un total de 10 colegios. En caso de que haga m\u00e1s solicitudes se considerar\u00e1 duplicidad y se anular\u00e1n todas.<\/span><\/p>\n<p><span style=\"font-family: arial, sans-serif;\">El c\u00f3digo de nuestro centro es:<\/span><\/p>\n<h4><strong>46013116<\/strong>\u00a0Colegio Salesianos San Juan Bosco<\/h4>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbNORMATIVA\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/03\/Normativa-Aplicable-23-24.pdf\" rel=\"attachment wp-att-18973\">Normativa Aplicable 23-24<\/a><\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][et_pb_text disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbTexto documentos\u00bb _builder_version=\u00bb4.26.0&#8243; text_text_color=\u00bb#d6d6d6&#8243; link_option_url=\u00bbhttps:\/\/forms.gle\/nZLdEXNiGAHCnVqk6&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h6><a href=\"https:\/\/forms.gle\/kicyzoyg313YkyaWA\"><span style=\"font-family: Arial, Helvetica, Arial, Lucida, sans-serif; font-size: 22px;\">FORMULARIO CITA PREVIA PROCESO ADMISI\u00d3N<\/span><\/a><\/h6>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbTexto documentos\u00bb _builder_version=\u00bb4.25.0&#8243; text_text_color=\u00bb#d6d6d6&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><span style=\"font-family: Arial, Helvetica, Arial, Lucida, sans-serif; font-size: 22px;\">PREGUNTAS FRECUENTES<\/span><\/h1>\n<p>[\/et_pb_text][et_pb_tabs disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbPesta\u00f1as FAQ\u00bb _builder_version=\u00bb4.25.0&#8243; background_color=\u00bb#f9d6a4&#8243; disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_tab title=\u00bbADMISI\u00d3N\u00bb _builder_version=\u00bb4.20.2&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>\u00bfEl proceso de admisi\u00f3n es el mismo para los colegios p\u00fablicos y <\/strong><strong>concertados?<\/strong><br \/>S\u00ed. La admisi\u00f3n en centros sostenidos con fondos p\u00fablicos, tanto p\u00fablicos como concertados, viene regulada por la misma normativa auton\u00f3mica y, por lo tanto, en estos centros se aplican los mismos criterios de baremaci\u00f3n.<\/p>\n<p><strong>\u00bfC\u00f3mo puedo tramitar la solicitud?<\/strong><br \/>El procedimiento de admisi\u00f3n en las etapas de Educaci\u00f3n Infantil, Primaria, ESO, Bachillerato y FP para el pr\u00f3ximo curso se realizar\u00e1 de forma telem\u00e1tica a traves de la p\u00e1gina de Conseller\u00eda www.telematricula.es. El colegio dispondr\u00e1 de terminales en sus instalaciones para aquellas familias que deseen tramitarlo en el propio colegio. Adem\u00e1s tendr\u00e1n la asistencia de nuestro personal para realizar correctamente la solicitud de admisi\u00f3n y evitar errores en el proceso.<\/p>\n<p><strong>\u00bfCu\u00e1ndo tengo que tramitar la solicitud?<\/strong><br \/>Para las etapas de INFANTIL y PRIMARIA del 20 al 28 de abril de 2023. Y para las etapas de ESO y BACHILLERATO del 4 al 12 de mayo de 2023.<\/p>\n<p><strong>\u00bfCu\u00e1ntos centros puedo pedir?<\/strong><br \/>Podr\u00e1 solicitar como m\u00e1ximo, un total de 10 centros por orden de preferencia, todos en la misma solicitud.<\/p>\n<p><strong>\u00bfSi solicito diferentes centros, debo presentar una solicitud en cada uno de <\/strong><strong>ellos?<\/strong><br \/>No. S\u00f3lo se debe presentar una solicitud en el centro solicitado como primera opci\u00f3n. En caso de que se presente m\u00e1s de una solicitud, se considera\u00a0 duplicidad y autom\u00e1ticamente el sistema las anula por lo que ser\u00e1 adjudicada una plaza de oficio al alumno o alumna.<\/p>\n<p><strong>\u00bfSi no hay ninguna vacante para el curso que debe hacer mi hijo o hija, <\/strong><strong>puedo presentar la solicitud de admisi\u00f3n?<\/strong><br \/>Si. Por supuesto, aunque no haya ninguna vacante, el centro tiene la obligaci\u00f3n de admitir todas las solicitudes que se le presentan. Adem\u00e1s, hay que tener en cuenta que quiz\u00e1s a lo largo del proceso de preinscripci\u00f3n y matr\u00edcula se puede generar alguna vacante que no aparece al principio. En este caso la plaza ser\u00e1 ofrecida, por riguroso orden, a los solicitantes que han quedado en lista de espera.<\/p>\n<p><strong>\u00bfCu\u00e1les son los l\u00edmites de zona?<\/strong><br \/>Todav\u00eda no se han publicado por parte de la Conseller\u00eda. Actualizaremos esta secci\u00f3n en el momento tengamos la informaci\u00f3n.<\/p>\n<p><strong>\u00bfCu\u00e1les son los criterios para la valoraci\u00f3n de las solicitudes?<\/strong><\/p>\n<p>1. Existencia de hermanos o hermanas matriculados en el centro.<br \/>2. Padre, madre o tutores legales trabajadores en el centro docente.<br \/>3. Proximidad del domicilio o del lugar de trabajo de alguno de sus padres, madres o tutores legales.<br \/>4. Renta per c\u00e1pita de la unidad familiar.<br \/>5. Condici\u00f3n legal de familia numerosa.<br \/>6. Concurrencia de discapacidad en el alumnado, en sus padres, madres, tutores o hermanos o hermanas.<br \/>7. Familia monoparental.<br \/>8. Expediente acad\u00e9mico, solo en ense\u00f1anzas postobligatorias.<\/p>\n<p><strong>Tengo una discapacidad, pero no tengo el certificado de bienestar social,<\/strong><br \/><strong>\u00bfpuedo presentar la solicitud de discapacidad como documento para que <\/strong><strong>me cuente en la baremaci\u00f3n?<\/strong><br \/>Para acreditar la condici\u00f3n de discapacidad y \u00e9sta se pueda baremar, es necesario aportar el dictamen t\u00e9cnico facultativo que indica el tipo de discapacidad y el grado de la misma. Es en funci\u00f3n del grado de la misma cuando se pueda baremar. T\u00e9ngase en cuenta adem\u00e1s que la solicitud de discapacidad puede aprobarse o denegarse, por lo que no ser\u00e1 v\u00e1lida para el proceso de admisiones.<\/p>\n<p><strong>\u00bfQu\u00e9 ocurre ante igualdad de puntuaci\u00f3n entre dos solicitudes?<\/strong><br \/>Los empates que, si es el caso, se produzcan se dirimir\u00e1n aplicando sucesivamente la mayor puntuaci\u00f3n obtenida en los criterios siguientes y en el orden establecido hasta el momento en que se produzca el desempate:<br \/>1. Existencia de hermanos o hermanas, u otra persona que se encuentre en situaci\u00f3n de acogida familiar o en guarda con fines de adopci\u00f3n, matriculados en el centro.<br \/>2. Padre, madre o tutores legales trabajadores del centro docente.<br \/>3. Proximidad del domicilio donde resida el alumno o alumna o del puesto de trabajo de alguno de sus padres, madres o tutores legales.<br \/>4. Condici\u00f3n de persona destinataria de la renta valenciana de inclusi\u00f3n.<br \/>5. Renta per c\u00e1pita de la unidad familiar.<br \/>6. Condici\u00f3n legal de familia numerosa.<br \/>7. Concurrencia de discapacidad en el alumnado, en sus padres, madres, tutores legales, hermanos o hermanas.<br \/>8. Familia monoparental.<br \/>9. Expediente acad\u00e9mico, solo en ense\u00f1anzas post obligatorias.<br \/>10. En las situaciones de empate que se produzcan despu\u00e9s de aplicar estos criterios, la ordenaci\u00f3n de las solicitudes afectadas se har\u00e1 por sorteo p\u00fablico, de acuerdo con el procedimiento que establezca la conselleria competente en materia de educaci\u00f3n.<\/p>\n<p><strong>\u00bfQu\u00e9 es el requisito acad\u00e9mico?<\/strong><br \/>Para la admisi\u00f3n en la Educaci\u00f3n Secundaria Obligatoria y Bachillerato se requiere que el alumno cumpla con el Requisito Acad\u00e9mico, es decir, est\u00e9 en\u00a0condiciones de promocionar a la etapa siguiente. Aquellos alumnos que hayan presentado solicitud para 1\u00ba de la ESO deber\u00e1n solicitar en el colegio de origen cuando les den las notas a final de curso un Certificado de Promoci\u00f3n a la E.S.O. y entregarlo en el Colegio donde ha presentado la solicitud, en la fecha que se indique en la resoluci\u00f3n de escolarizaci\u00f3n.<br \/>En el caso de 1\u00ba de Bachillerato, cuando finalicen 4\u00ba de la E.S.O, deber\u00e1n solicitar un Certificado de Nota Media de la E.S.O. para admisi\u00f3n y entregarlo en el Colegio donde ha presentado la solicitud, en la fecha que se indique en la resoluci\u00f3n de escolarizaci\u00f3n.<br \/>El resto de cursos 2\u00ba, 3\u00ba y 4\u00ba de la E.S.O. y 2\u00ba de Bachillerato, deber\u00e1n aportar en las mismas fechas un certificado acad\u00e9mico que permita comprobar que est\u00e1n en condiciones de promocionar.<\/p>\n<p>Actualizado 14 de marzo de 2023.<\/p>\n<p>[\/et_pb_tab][\/et_pb_tabs][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2019\/09\/40488219_396101174261420_9115812302835285209_n1.jpg\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_button button_url=\u00bbhttps:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScNjBmuPGZRw-L3fvCNcHUheKlTdJUzL4FKeG1Gp9MX1ifg8w\/viewform?usp=dialog \u00bb button_text=\u00bbFORMULARIO  MATR\u00cdCULA 1\u00ba BACHILLERATO\u00bb button_alignment=\u00bbcenter\u00bb disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbACCESO FORMULARIO matr\u00edcula 1\u00ba bach\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb15px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_bg_use_color_gradient=\u00bbon\u00bb button_bg_color_gradient_type=\u00bbcircular\u00bb button_bg_color_gradient_direction=\u00bb124deg\u00bb button_bg_color_gradient_stops=\u00bb#ffffff 0%|#93ffff 100%\u00bb button_border_width=\u00bb2px\u00bb button_border_color=\u00bb#0C71C3&#8243; button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbABeeZee|700|||||||\u00bb button_icon=\u00bb&#x41;||divi||400&#8243; hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/forms.gle\/KN51PrMof8X9ZqwdA\u00bb button_text=\u00bbFORMULARIO CITA PREVIA PARA ADMISI\u00d3N ESO-BACH ASISTIDA EN EL COLEGIO\u00bb button_alignment=\u00bbcenter\u00bb disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbACCESO FORMULARIO ADMISI\u00d3N\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb15px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_bg_use_color_gradient=\u00bbon\u00bb button_bg_color_gradient_type=\u00bbcircular\u00bb button_bg_color_gradient_direction=\u00bb124deg\u00bb button_bg_color_gradient_stops=\u00bb#ffffff 0%|#c5ff93 100%\u00bb button_border_width=\u00bb2px\u00bb button_border_color=\u00bb#0C71C3&#8243; button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbABeeZee|700|||||||\u00bb button_icon=\u00bb&#x41;||divi||400&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_accordion open_toggle_background_color=\u00bbrgba(224,153,0,0.15)\u00bb closed_toggle_background_color=\u00bbrgba(136,221,0,0.44)\u00bb icon_color=\u00bb#E02B20&#8243; icon_font_size=\u00bb30px\u00bb admin_label=\u00bbMANUALES MATR\u00cdCULA\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb toggle_font_size=\u00bb15px\u00bb toggle_line_height=\u00bb1.1em\u00bb closed_toggle_font_size=\u00bb13px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bbMANUAL APP M\u00d3VIL MATR\u00cdCULA VIRTUAL 3 A\u00d1OS \u00bb open=\u00bbon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/06\/Manual-MV-desde-app-VSJB-1.pdf\" rel=\"attachment wp-att-24792\">Manual APP MATR\u00cdCULA 3 A\u00d1OS<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbMANUAL WEB MATR\u00cdCULA VIRTUAL 3 A\u00d1OS \u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/06\/Manual-MV-desde-web-VSJB-comprimido.pdf\" rel=\"attachment wp-att-24793\">Manual WEB MATR\u00cdCULA 3 A\u00d1OS<\/a><\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][et_pb_button button_url=\u00bbhttps:\/\/valenciasjb.salesianos.edu\/colegio\/optatividad\/\u00bb button_text=\u00bbACCESO A ELECCI\u00d3N DE OPTATIVAS EN ESO\u00bb disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbACCESO OPTATIVIDAD ESO\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb18px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bbrgba(140,174,247,0.33)\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbAlata||||||||\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/valenciasjb.salesianos.edu\/colegio\/optatividad\/\u00bb button_text=\u00bbACCESO A ELECCI\u00d3N DE OPTATIVAS BACHILLERATO\u00bb disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbACCESO OPTATIVIDAD  BACH\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb18px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bbrgba(140,174,247,0.33)\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbAlata||||||||\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_image src=\u00bbhttps:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/04\/eso-batch.jpeg\u00bb title_text=\u00bbeso batch\u00bb url=\u00bbhttps:\/\/portal.edu.gva.es\/telematricula\/\u00bb url_new_window=\u00bbon\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.19.5&#8243; _module_preset=\u00bbdefault\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Admisi\u00f3n y Matriculaci\u00f3n 2026-2027 Documentos Datos del colegio: (VALENCIA) &#8211; COLEGIO SALESIANOS SAN JUAN BOSCO con c\u00f3digo de centro 46013116 \u00a0 \u00a0RESOLUCI\u00d3N de 25 de febrero de 2026, de la Direcci\u00f3n General de Centros Docentes, por la que se establece el calendario y se dictan instrucciones respecto al procedimiento de admisi\u00f3n del alumnado en los [&hellip;]<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-8567","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>matriculaci\u00f3n - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"description\" content=\"Calendarios y enlaces de la matruculaci\u00f3n 2020\/21\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"matriculaci\u00f3n - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"Calendarios y enlaces de la matruculaci\u00f3n 2020\/21\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:05:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/matriculacion\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/matriculacion\\\/\",\"name\":\"matriculaci\u00f3n - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"datePublished\":\"2018-03-27T10:05:22+00:00\",\"dateModified\":\"2026-07-08T12:05:34+00:00\",\"description\":\"Calendarios y enlaces de la matruculaci\u00f3n 2020\\\/21\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/matriculacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/matriculacion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/matriculacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"matriculaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"matriculaci\u00f3n - Colegio San Juan Bosco Valencia","description":"Calendarios y enlaces de la matruculaci\u00f3n 2020\/21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/","og_locale":"es_ES","og_type":"article","og_title":"matriculaci\u00f3n - Colegio San Juan Bosco Valencia","og_description":"Calendarios y enlaces de la matruculaci\u00f3n 2020\/21","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_modified_time":"2026-07-08T12:05:34+00:00","twitter_card":"summary_large_image","twitter_site":"@SalesianosVSJB","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/","name":"matriculaci\u00f3n - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"datePublished":"2018-03-27T10:05:22+00:00","dateModified":"2026-07-08T12:05:34+00:00","description":"Calendarios y enlaces de la matruculaci\u00f3n 2020\/21","breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/matriculacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"matriculaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/8567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=8567"}],"version-history":[{"count":152,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/8567\/revisions"}],"predecessor-version":[{"id":25245,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/8567\/revisions\/25245"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=8567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}