{"id":14443,"date":"2020-05-17T11:32:51","date_gmt":"2020-05-17T10:32:51","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?p=14443"},"modified":"2020-10-12T11:45:18","modified_gmt":"2020-10-12T10:45:18","slug":"actividades-ampas-2019-2020","status":"publish","type":"post","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/","title":{"rendered":"ACTIVIDADES AMPAS 2019\/2020"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">MENSAJE AMPAS:<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Estimadas familias:<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Esperamos y deseamos que os encontr\u00e9is bien, y llevando lo mejor posible esta situaci\u00f3n que estamos viviendo en los \u00faltimos meses.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Desde AMPAS queremos dirigirnos a vosotros, familias del cole, para aclarar una cuesti\u00f3n que se nos ha planteado. Creemos que ser\u00e1 bueno para todos explicarla.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">\u00bfPor qu\u00e9 AMPAS pasa la segunda parte de la cuota si el cole est\u00e1 cerrado?<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Lo explicamos:<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">En la Asamblea General de principio de curso se presentan las cuentas del curso anterior y el presupuesto para este curso que a\u00fan no ha terminado. Todas las actividades desde Septiembre hasta Junio est\u00e1n programadas y presupuestadas.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Para realizar el presupuesto del curso se cuenta con la cuota de los 36 euros POR FAMILIA que se fracciona en 2 pagos pero que es \u00fanica.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">El cole ha cerrado sus puertas, pero sigue en marcha y a todo gas. Y AMPAS, representando a las familias, tambi\u00e9n.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Para dar luz a la cuesti\u00f3n planteada, os adjuntamos un listado de actividades que ha organizado o en las que ha participado AMPAS hasta el momento, y que siempre van enfocadas a mejorar la experiencia en el colegio de nuestros hijos y las familias.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Como nos contaba el Director del Colegio en su QE del d\u00eda 06\/04\/2020 con asunto \u201cAportaci\u00f3n voluntaria abril\u201d, esta crisis afecta tambi\u00e9n econ\u00f3micamente a nuestro colegio.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Hay familias como las nuestras a las que esta crisis est\u00e1 golpeando muy duramente. Familias que forman parte de nuestro cole.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">En una video-junta escuchamos: \u201cNo estamos todos en el mismo barco. Estamos todos en el mismo mar, pero algunos van con lancha, otros con bote y otros no tienen a d\u00f3nde cogerse\u2026 y en nuestra comunidad educativa no va a haber ning\u00fan naufrago.\u201d<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Los profesionales de nuestro cole no iban a dejar a nadie s\u00f3lo.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Y la junta de AMPAS, en nuestra obligaci\u00f3n y responsabilidad estatutaria para con nuestros alumnos y familias, tampoco.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">En nuestro cole no va a haber n\u00e1ufragos.<\/div>\n<div dir=\"auto\">Ha habido un cambio de prioridades as\u00ed es que nos pusimos a disposici\u00f3n del cole para ayudar econ\u00f3micamente, seguir con nuestras actividades o colaborando con nuestros v\u00eddeos de \u00e1nimo, en estos d\u00edas y en todos los que est\u00e1n por venir.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Y a eso estamos dedicando nuestros esfuerzos ahora que el cole \u201cest\u00e1 cerrado\u201d.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Os necesitamos.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Mucho \u00e1nimo y gracias a todos!!<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">La Junta de Ampas<\/div>\n<div dir=\"auto\"><a class=\"oajrlxb2 g5ia77u1 qu0x051f esr5mh6w e9989ue4 r7d6kgcz rq0escxv nhd2j8a9 nc684nl6 p7hjln8o kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x jb3vyjys rz4wbd8a qt6c0cv9 a8nywdso i1ao9s8h esuyzwwr f1sip0of lzcic4wl q66pz984 gpro0wi8 b1v8xokw\" role=\"link\" href=\"https:\/\/www.facebook.com\/hashtag\/ampassjb?__eep__=6&amp;__cft__[0]=AZUHaQRmmKOeR8rG0L3w6DfRx2gcZU0y2zbyGp6DfLlLqr-GgELkJNVqAdz0ag7uUC_tB0FCzS5v49iuSrrtWXVpUpo8xyVTxXnk80X9ZULGeszwtZNBGRaJd9gpzXRIBCDAU9Rjp-9rEtKSlvmVgy9jKRC5Z5tvtDwg0JG8wLeuRQ&amp;__tn__=*NK-R\">#ampassjb<\/a><\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-14452\" src=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/actividades-ampas-1-768x1024.jpg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/actividades-ampas-1-768x1024.jpg 768w, https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/actividades-ampas-1-480x640.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 768px, 100vw\" \/><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>MENSAJE AMPAS: Estimadas familias: Esperamos y deseamos que os encontr\u00e9is bien, y llevando lo mejor posible esta situaci\u00f3n que estamos viviendo en los \u00faltimos meses. Desde AMPAS queremos dirigirnos a vosotros, familias del cole, para aclarar una cuesti\u00f3n que se nos ha planteado. Creemos que ser\u00e1 bueno para todos explicarla. \u00bfPor qu\u00e9 AMPAS pasa la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":14444,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30,9,32],"tags":[33],"class_list":["post-14443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ampas_actividades","category-noticias","category-noticias-ampas","tag-ampassjb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ACTIVIDADES AMPAS 2019\/2020 - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"description\" content=\"Estimadas familias:Esperamos y deseamos que os encontr\u00e9is bien, y llevando lo mejor posible esta situaci\u00f3n que estamos viviendo \u00faltimamente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACTIVIDADES AMPAS 2019\/2020 - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"Estimadas familias:Esperamos y deseamos que os encontr\u00e9is bien, y llevando lo mejor posible esta situaci\u00f3n que estamos viviendo \u00faltimamente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-17T10:32:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-12T10:45:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/actividades-ampas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"843\" \/>\n\t<meta property=\"og:image:height\" content=\"1124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ampasvsjb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ampasvsjb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/\"},\"author\":{\"name\":\"ampasvsjb\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/0726ac8cfbb8c3fbd6c5e1c72693053d\"},\"headline\":\"ACTIVIDADES AMPAS 2019\\\/2020\",\"datePublished\":\"2020-05-17T10:32:51+00:00\",\"dateModified\":\"2020-10-12T10:45:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/\"},\"wordCount\":410,\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/actividades-ampas.jpg\",\"keywords\":[\"#ampassjb\"],\"articleSection\":[\"AMPAS Actividades\",\"Noticias\",\"Noticias AMPAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/\",\"name\":\"ACTIVIDADES AMPAS 2019\\\/2020 - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/actividades-ampas.jpg\",\"datePublished\":\"2020-05-17T10:32:51+00:00\",\"dateModified\":\"2020-10-12T10:45:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/0726ac8cfbb8c3fbd6c5e1c72693053d\"},\"description\":\"Estimadas familias:Esperamos y deseamos que os encontr\u00e9is bien, y llevando lo mejor posible esta situaci\u00f3n que estamos viviendo \u00faltimamente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/actividades-ampas.jpg\",\"contentUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/actividades-ampas.jpg\",\"width\":843,\"height\":1124},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/actividades-ampas-2019-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACTIVIDADES AMPAS 2019\\\/2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/0726ac8cfbb8c3fbd6c5e1c72693053d\",\"name\":\"ampasvsjb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g\",\"caption\":\"ampasvsjb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ACTIVIDADES AMPAS 2019\/2020 - Colegio San Juan Bosco Valencia","description":"Estimadas familias:Esperamos y deseamos que os encontr\u00e9is bien, y llevando lo mejor posible esta situaci\u00f3n que estamos viviendo \u00faltimamente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/","og_locale":"es_ES","og_type":"article","og_title":"ACTIVIDADES AMPAS 2019\/2020 - Colegio San Juan Bosco Valencia","og_description":"Estimadas familias:Esperamos y deseamos que os encontr\u00e9is bien, y llevando lo mejor posible esta situaci\u00f3n que estamos viviendo \u00faltimamente.","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_published_time":"2020-05-17T10:32:51+00:00","article_modified_time":"2020-10-12T10:45:18+00:00","og_image":[{"width":843,"height":1124,"url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/actividades-ampas.jpg","type":"image\/jpeg"}],"author":"ampasvsjb","twitter_card":"summary_large_image","twitter_creator":"@SalesianosVSJB","twitter_site":"@SalesianosVSJB","twitter_misc":{"Escrito por":"ampasvsjb","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/#article","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/"},"author":{"name":"ampasvsjb","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/0726ac8cfbb8c3fbd6c5e1c72693053d"},"headline":"ACTIVIDADES AMPAS 2019\/2020","datePublished":"2020-05-17T10:32:51+00:00","dateModified":"2020-10-12T10:45:18+00:00","mainEntityOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/"},"wordCount":410,"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/actividades-ampas.jpg","keywords":["#ampassjb"],"articleSection":["AMPAS Actividades","Noticias","Noticias AMPAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/","name":"ACTIVIDADES AMPAS 2019\/2020 - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/#primaryimage"},"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/actividades-ampas.jpg","datePublished":"2020-05-17T10:32:51+00:00","dateModified":"2020-10-12T10:45:18+00:00","author":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/0726ac8cfbb8c3fbd6c5e1c72693053d"},"description":"Estimadas familias:Esperamos y deseamos que os encontr\u00e9is bien, y llevando lo mejor posible esta situaci\u00f3n que estamos viviendo \u00faltimamente.","breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/#primaryimage","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/actividades-ampas.jpg","contentUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/actividades-ampas.jpg","width":843,"height":1124},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/actividades-ampas-2019-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"ACTIVIDADES AMPAS 2019\/2020"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/0726ac8cfbb8c3fbd6c5e1c72693053d","name":"ampasvsjb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g","caption":"ampasvsjb"}}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=14443"}],"version-history":[{"count":4,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14443\/revisions"}],"predecessor-version":[{"id":14453,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14443\/revisions\/14453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/14444"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=14443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=14443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=14443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}