{"id":14792,"date":"2021-02-01T16:10:33","date_gmt":"2021-02-01T15:10:33","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?p=14792"},"modified":"2021-02-01T16:13:16","modified_gmt":"2021-02-01T15:13:16","slug":"tercera-jornada-de-webinar","status":"publish","type":"post","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/","title":{"rendered":"TERCERA JORNADA DE WEBINAR DE AMPAS"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Dando continuidad a las formaciones de final de a\u00f1o, hemos continuado el a\u00f1o 2021 con la tercera jornada de webinar de formaci\u00f3n para familias desde AMPAS. Este formato nos permite llegar a un mayor n\u00famero de familias, ya no s\u00f3lo de forma directa, en el momento de la sesi\u00f3n, sino que aquellas que no pudieron puedan beneficiarse de la misma.<\/p>\n<p>Susana de la Poza Pasto es pedagoga, maestra de educaci\u00f3n especial y tutora en un aula espec\u00edfica en un centro ordinario. Explic\u00f3 la figura de la PT en las aulas y qui\u00e9nes son los alumnos que tienen necesidades especiales. Adem\u00e1s nos dio ejemplos pr\u00e1cticos de ayuda para casa a las familias.<\/p>\n<p>Si no pudiste asistir en directo a la tercera Jornada de Webinar de AMPAS o quieres volver a verlo puedes hacerlo desde el siguiente enlace:<\/p>\n<p><a href=\"https:\/\/youtu.be\/xT0FJAEhSmk\">Estrategias y pautas para el alumnado con necesidades educativas espec\u00edficas &#8211; YouTube<\/a><\/p>\n<p>Os animamos a participar de las siguientes formaciones promovidas desde AMPAS. Pod\u00e9is remitir preguntas para realizar a los ponentes durante los d\u00edas previos a la formaci\u00f3n. Estad atentos a nuestros canales de comunicaci\u00f3n habituales y Facebook para saber las pr\u00f3ximas fechas.<\/p>\n<p>Os recordamos que la tem\u00e1tica ha sido elegida por las propias familias y que tendr\u00e1 su continuaci\u00f3n en las pr\u00f3ximas semanas:<\/p>\n<table width=\"576\">\n<tbody>\n<tr>\n<td width=\"491\"><strong>Webinar<\/strong><\/td>\n<td width=\"85\"><strong>Fecha<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"491\"><a href=\"https:\/\/bit.ly\/WDPositiva\">Gesti\u00f3n documental y disciplina positiva<\/a><\/td>\n<td width=\"85\">26\/11\/2020<\/td>\n<\/tr>\n<tr>\n<td width=\"491\"><a href=\"https:\/\/youtu.be\/iOBoQFzFNhk\">C\u00f3mo utilizar Google drive, plataformas como Zoom, Google Meet, etc.<\/a><\/td>\n<td width=\"85\">10\/12\/2020<\/td>\n<\/tr>\n<tr>\n<td width=\"491\"><a href=\"https:\/\/youtu.be\/xT0FJAEhSmk\">Estrategias y pautas para el alumnado con necesidades educativas espec\u00edficas<\/a><\/td>\n<td width=\"85\">28\/01\/2021<\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Pautas para crear h\u00e1bitos de lectura y ocio<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">C\u00f3mo fomentar la autonom\u00eda de tus hijos e hijas para hacer deberes<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Autoconocimiento para adolescentes<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">C\u00f3mo educar para la paz desde casa<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Gesti\u00f3n del tiempo para adolescentes<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Medidas pr\u00e1cticas para una buena higiene y prevenci\u00f3n COVID<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Ejercicios f\u00edsicos en casa para ni\u00f1os y ni\u00f1as<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Econom\u00eda dom\u00e9stica y presupuesto familiar<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div id=\"attachment_14794\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14794\" class=\"wp-image-14794 size-large\" src=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/02\/Destacada-Estrategia-Familias-ANEE-1024x575.jpg\" alt=\"Car\u00e1tula presentaci\u00f3n\" width=\"1024\" height=\"575\" srcset=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/02\/Destacada-Estrategia-Familias-ANEE-980x550.jpg 980w, https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/02\/Destacada-Estrategia-Familias-ANEE-480x269.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><p id=\"caption-attachment-14794\" class=\"wp-caption-text\">Tercera Jornada de Webinar AMPAS: Estrategias y Pautas para las familias con necesidades educativas especiales. Susana de la Poza Pastor<\/p><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Dando continuidad a las formaciones de final de a\u00f1o, hemos continuado el a\u00f1o 2021 con la tercera jornada de webinar de formaci\u00f3n para familias desde AMPAS. Este formato nos permite llegar a un mayor n\u00famero de familias, ya no s\u00f3lo de forma directa, en el momento de la sesi\u00f3n, sino que aquellas que no pudieron [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":14793,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30,32],"tags":[33,47],"class_list":["post-14792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ampas_actividades","category-noticias-ampas","tag-ampassjb","tag-webinar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TERCERA JORNADA DE WEBINAR DE AMPAS - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"description\" content=\"Tercera Jornada Webinar Formaci\u00f3n AMPAS. La figura de la PT en las aulas y qui\u00e9nes son los alumnos que tienen necesidades especiales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TERCERA JORNADA DE WEBINAR DE AMPAS - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"Tercera Jornada Webinar Formaci\u00f3n AMPAS. La figura de la PT en las aulas y qui\u00e9nes son los alumnos que tienen necesidades especiales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T15:10:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-01T15:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/02\/pegatina.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1968\" \/>\n\t<meta property=\"og:image:height\" content=\"1248\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ampasvsjb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ampasvsjb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/\"},\"author\":{\"name\":\"ampasvsjb\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/0726ac8cfbb8c3fbd6c5e1c72693053d\"},\"headline\":\"TERCERA JORNADA DE WEBINAR DE AMPAS\",\"datePublished\":\"2021-02-01T15:10:33+00:00\",\"dateModified\":\"2021-02-01T15:13:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/\"},\"wordCount\":361,\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/pegatina.png\",\"keywords\":[\"#ampassjb\",\"#webinar\"],\"articleSection\":[\"AMPAS Actividades\",\"Noticias AMPAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/\",\"name\":\"TERCERA JORNADA DE WEBINAR DE AMPAS - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/pegatina.png\",\"datePublished\":\"2021-02-01T15:10:33+00:00\",\"dateModified\":\"2021-02-01T15:13:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/0726ac8cfbb8c3fbd6c5e1c72693053d\"},\"description\":\"Tercera Jornada Webinar Formaci\u00f3n AMPAS. La figura de la PT en las aulas y qui\u00e9nes son los alumnos que tienen necesidades especiales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/pegatina.png\",\"contentUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/pegatina.png\",\"width\":1968,\"height\":1248},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/tercera-jornada-de-webinar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TERCERA JORNADA DE WEBINAR DE AMPAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/0726ac8cfbb8c3fbd6c5e1c72693053d\",\"name\":\"ampasvsjb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g\",\"caption\":\"ampasvsjb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TERCERA JORNADA DE WEBINAR DE AMPAS - Colegio San Juan Bosco Valencia","description":"Tercera Jornada Webinar Formaci\u00f3n AMPAS. La figura de la PT en las aulas y qui\u00e9nes son los alumnos que tienen necesidades especiales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/","og_locale":"es_ES","og_type":"article","og_title":"TERCERA JORNADA DE WEBINAR DE AMPAS - Colegio San Juan Bosco Valencia","og_description":"Tercera Jornada Webinar Formaci\u00f3n AMPAS. La figura de la PT en las aulas y qui\u00e9nes son los alumnos que tienen necesidades especiales.","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_published_time":"2021-02-01T15:10:33+00:00","article_modified_time":"2021-02-01T15:13:16+00:00","og_image":[{"width":1968,"height":1248,"url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/02\/pegatina.png","type":"image\/png"}],"author":"ampasvsjb","twitter_card":"summary_large_image","twitter_creator":"@SalesianosVSJB","twitter_site":"@SalesianosVSJB","twitter_misc":{"Escrito por":"ampasvsjb","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/#article","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/"},"author":{"name":"ampasvsjb","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/0726ac8cfbb8c3fbd6c5e1c72693053d"},"headline":"TERCERA JORNADA DE WEBINAR DE AMPAS","datePublished":"2021-02-01T15:10:33+00:00","dateModified":"2021-02-01T15:13:16+00:00","mainEntityOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/"},"wordCount":361,"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/02\/pegatina.png","keywords":["#ampassjb","#webinar"],"articleSection":["AMPAS Actividades","Noticias AMPAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/","name":"TERCERA JORNADA DE WEBINAR DE AMPAS - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/#primaryimage"},"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/02\/pegatina.png","datePublished":"2021-02-01T15:10:33+00:00","dateModified":"2021-02-01T15:13:16+00:00","author":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/0726ac8cfbb8c3fbd6c5e1c72693053d"},"description":"Tercera Jornada Webinar Formaci\u00f3n AMPAS. La figura de la PT en las aulas y qui\u00e9nes son los alumnos que tienen necesidades especiales.","breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/#primaryimage","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/02\/pegatina.png","contentUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/02\/pegatina.png","width":1968,"height":1248},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/tercera-jornada-de-webinar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"TERCERA JORNADA DE WEBINAR DE AMPAS"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/0726ac8cfbb8c3fbd6c5e1c72693053d","name":"ampasvsjb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g","caption":"ampasvsjb"}}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=14792"}],"version-history":[{"count":1,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14792\/revisions"}],"predecessor-version":[{"id":14795,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14792\/revisions\/14795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/14793"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=14792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=14792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=14792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}