{"id":14973,"date":"2021-03-05T17:55:52","date_gmt":"2021-03-05T16:55:52","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?p=14973"},"modified":"2021-03-05T22:03:36","modified_gmt":"2021-03-05T21:03:36","slug":"4-webinar-ampas-autoconocimiento-para-adolescentes","status":"publish","type":"post","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/","title":{"rendered":"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Formaci\u00f3n.<\/p>\n<p>Esta semana hemos realizado el segundo Webinar de 2021 de formaci\u00f3n para las familias con una gran acogida.<\/p>\n<p>Amparo P\u00e9rez Ribes es formadora en Inteligencia Emocional, licenciada en Psicopedagog\u00eda y Pedagog\u00eda por la Universidad de Valencia y Formadora voluntaria de Desata tu Potencial. Nuestros hijos adolescentes son como \u201cextraterrestres\u201d para nosotros y muchas veces olvidamos conectar con su \u201cyo\u201d interior. Debemos entrenar pues nuestro autoconocimiento.<\/p>\n<p>Si no pudiste asistir en directo al Webinar o quieres volver a verlo puedes hacerlo desde el siguiente enlace:<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=bCfKOIHstVg\">Autoconocimiento para Adolescentes.<\/a><\/p>\n<p>Os animamos a participar de las siguientes formaciones promovidas desde AMPAS y cuya tem\u00e1tica ha sido elegida por las propias familias y que tendr\u00e1 su continuaci\u00f3n en las pr\u00f3ximas semanas:<\/p>\n<table width=\"576\">\n<tbody>\n<tr>\n<td width=\"491\"><strong>Webinar<\/strong><\/td>\n<td width=\"85\"><strong>Fecha<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"491\"><a href=\"https:\/\/bit.ly\/WDPositiva\">Gesti\u00f3n documental y disciplina positiva<\/a><\/td>\n<td width=\"85\">26\/11\/2020<\/td>\n<\/tr>\n<tr>\n<td width=\"491\"><a href=\"https:\/\/youtu.be\/iOBoQFzFNhk\">C\u00f3mo utilizar Google drive, plataformas como Zoom, Google Meet, etc.<\/a><\/td>\n<td width=\"85\">10\/12\/2020<\/td>\n<\/tr>\n<tr>\n<td width=\"491\"><a href=\"https:\/\/youtu.be\/xT0FJAEhSmk\">Estrategias y pautas para el alumnado con necesidades educativas espec\u00edficas<\/a><\/td>\n<td width=\"85\">28\/01\/2021<\/td>\n<\/tr>\n<tr>\n<td width=\"491\"><a href=\"https:\/\/www.youtube.com\/watch?v=bCfKOIHstVg\">Autoconocimiento para adolescentes<\/a><\/td>\n<td width=\"85\">04\/03\/2021<\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Pautas para crear h\u00e1bitos de lectura y ocio<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">C\u00f3mo fomentar la autonom\u00eda de tus hijos e hijas para hacer deberes<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">C\u00f3mo educar para la paz desde casa<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Gesti\u00f3n del tiempo para adolescentes<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Medidas pr\u00e1cticas para una buena higiene y prevenci\u00f3n COVID<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Ejercicios f\u00edsicos en casa para ni\u00f1os y ni\u00f1as<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<tr>\n<td width=\"491\">Econom\u00eda dom\u00e9stica y presupuesto familiar<\/td>\n<td width=\"85\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div id=\"attachment_14974\" style=\"width: 644px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14974\" class=\"wp-image-14974\" src=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/03\/Portada-Autoconocimiento-para-adolescentes-1024x574.jpg\" alt=\"\" width=\"634\" height=\"355\" \/><p id=\"caption-attachment-14974\" class=\"wp-caption-text\">Cuarta Jornada Formaci\u00f3n AMPAS: Autoconocimiento para Adolescentes por Amparo P\u00e9rez<\/p><\/div>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Formaci\u00f3n. Esta semana hemos realizado el segundo Webinar de 2021 de formaci\u00f3n para las familias con una gran acogida. Amparo P\u00e9rez Ribes es formadora en Inteligencia Emocional, licenciada en Psicopedagog\u00eda y Pedagog\u00eda por la Universidad de Valencia y Formadora voluntaria de Desata tu Potencial. Nuestros hijos adolescentes son como \u201cextraterrestres\u201d para nosotros y muchas veces [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":14975,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30,32],"tags":[],"class_list":["post-14973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ampas_actividades","category-noticias-ampas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"description\" content=\"Cuarta jornada de formaci\u00f3n AMPAS para las familias. Autoconocimiento para Adolescentes a cargo de Amparo P\u00e9rez, experta en Inteligencia Emocional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"Cuarta jornada de formaci\u00f3n AMPAS para las familias. Autoconocimiento para Adolescentes a cargo de Amparo P\u00e9rez, experta en Inteligencia Emocional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-05T16:55:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-05T21:03:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/03\/Destacada-Autoconocimiento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"531\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ampasvsjb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ampasvsjb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/\"},\"author\":{\"name\":\"ampasvsjb\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/0726ac8cfbb8c3fbd6c5e1c72693053d\"},\"headline\":\"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES\",\"datePublished\":\"2021-03-05T16:55:52+00:00\",\"dateModified\":\"2021-03-05T21:03:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/\"},\"wordCount\":248,\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Destacada-Autoconocimiento.jpg\",\"articleSection\":[\"AMPAS Actividades\",\"Noticias AMPAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/\",\"name\":\"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Destacada-Autoconocimiento.jpg\",\"datePublished\":\"2021-03-05T16:55:52+00:00\",\"dateModified\":\"2021-03-05T21:03:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/0726ac8cfbb8c3fbd6c5e1c72693053d\"},\"description\":\"Cuarta jornada de formaci\u00f3n AMPAS para las familias. Autoconocimiento para Adolescentes a cargo de Amparo P\u00e9rez, experta en Inteligencia Emocional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Destacada-Autoconocimiento.jpg\",\"contentUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Destacada-Autoconocimiento.jpg\",\"width\":531,\"height\":403},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/4-webinar-ampas-autoconocimiento-para-adolescentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/0726ac8cfbb8c3fbd6c5e1c72693053d\",\"name\":\"ampasvsjb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g\",\"caption\":\"ampasvsjb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES - Colegio San Juan Bosco Valencia","description":"Cuarta jornada de formaci\u00f3n AMPAS para las familias. Autoconocimiento para Adolescentes a cargo de Amparo P\u00e9rez, experta en Inteligencia Emocional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/","og_locale":"es_ES","og_type":"article","og_title":"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES - Colegio San Juan Bosco Valencia","og_description":"Cuarta jornada de formaci\u00f3n AMPAS para las familias. Autoconocimiento para Adolescentes a cargo de Amparo P\u00e9rez, experta en Inteligencia Emocional.","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_published_time":"2021-03-05T16:55:52+00:00","article_modified_time":"2021-03-05T21:03:36+00:00","og_image":[{"width":531,"height":403,"url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/03\/Destacada-Autoconocimiento.jpg","type":"image\/jpeg"}],"author":"ampasvsjb","twitter_card":"summary_large_image","twitter_creator":"@SalesianosVSJB","twitter_site":"@SalesianosVSJB","twitter_misc":{"Escrito por":"ampasvsjb","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/#article","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/"},"author":{"name":"ampasvsjb","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/0726ac8cfbb8c3fbd6c5e1c72693053d"},"headline":"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES","datePublished":"2021-03-05T16:55:52+00:00","dateModified":"2021-03-05T21:03:36+00:00","mainEntityOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/"},"wordCount":248,"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/03\/Destacada-Autoconocimiento.jpg","articleSection":["AMPAS Actividades","Noticias AMPAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/","name":"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/#primaryimage"},"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/03\/Destacada-Autoconocimiento.jpg","datePublished":"2021-03-05T16:55:52+00:00","dateModified":"2021-03-05T21:03:36+00:00","author":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/0726ac8cfbb8c3fbd6c5e1c72693053d"},"description":"Cuarta jornada de formaci\u00f3n AMPAS para las familias. Autoconocimiento para Adolescentes a cargo de Amparo P\u00e9rez, experta en Inteligencia Emocional.","breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/#primaryimage","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/03\/Destacada-Autoconocimiento.jpg","contentUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/03\/Destacada-Autoconocimiento.jpg","width":531,"height":403},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/4-webinar-ampas-autoconocimiento-para-adolescentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"4\u00ba WEBINAR: AUTOCONOCIMIENTO PARA ADOLESCENTES"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/0726ac8cfbb8c3fbd6c5e1c72693053d","name":"ampasvsjb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be990de11bab2de567b8fb079bb13b0b2ebe2aab5258b635f6286f7a56c0c6c5?s=96&d=mm&r=g","caption":"ampasvsjb"}}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=14973"}],"version-history":[{"count":3,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14973\/revisions"}],"predecessor-version":[{"id":14995,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14973\/revisions\/14995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/14975"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=14973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=14973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=14973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}