{"id":18945,"date":"2023-03-08T17:45:53","date_gmt":"2023-03-08T16:45:53","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?p=18945"},"modified":"2023-03-08T17:45:58","modified_gmt":"2023-03-08T16:45:58","slug":"el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023","status":"publish","type":"post","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/","title":{"rendered":"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.20.0&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<div id=\"resumen\"><strong>La valoraci\u00f3n de las donaciones realizadas de productos de primera necesidad asciende a 1362,92 euros. Esta es una muestra de ayuda y cari\u00f1o a nuestros hermanos m\u00e1s necesitados en nuestra lucha diaria por un mundo m\u00e1s justo y fraterno.<\/strong><\/div>\n<div>\u00a0<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbAutor (Texto)\u00bb _builder_version=\u00bb4.20.0&#8243; text_font=\u00bb||on||\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Redacci\u00f3n.<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.20.0&#8243; text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>El colegio quiere sumarse a este agradecimiento a todas las personas que con estos peque\u00f1os actos segu\u00eds haciendo posible el sue\u00f1o de Don Bosco en nuestro barrio de la Avenida de la Plata.<\/p>\n<p>Abrimos caminos.<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bboff|on|on\u00bb admin_label=\u00bbT\u00edtulo: Galer\u00eda de fotos (Texto)\u00bb _builder_version=\u00bb4.18.0&#8243; text_font=\u00bb|on|||\u00bb text_text_color=\u00bb#dc001b\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Galer\u00eda de im\u00e1genes<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb18948&#8243; posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#dc001b\u00bb hover_icon=\u00bb&#x54;||divi||400&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.20.0&#8243; hover_enabled=\u00bb0&#8243; pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_gallery][et_pb_video disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La valoraci\u00f3n de las donaciones realizadas de productos de primera necesidad asciende a 1362,92 euros. Esta es una muestra de ayuda y cari\u00f1o a nuestros hermanos m\u00e1s necesitados en nuestra lucha diaria por un mundo m\u00e1s justo y fraterno. \u00a0Redacci\u00f3n.El colegio quiere sumarse a este agradecimiento a todas las personas que con estos peque\u00f1os actos [&hellip;]<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":18948,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[14],"tags":[],"class_list":["post-18945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia_colegio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023 - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023 - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"La valoraci\u00f3n de las donaciones realizadas de productos de primera necesidad asciende a 1362,92 euros. Esta es una muestra de ayuda y cari\u00f1o a nuestros hermanos m\u00e1s necesitados en nuestra lucha diaria por un mundo m\u00e1s justo y fraterno. \u00a0Redacci\u00f3n.El colegio quiere sumarse a este agradecimiento a todas las personas que con estos peque\u00f1os actos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-08T16:45:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-08T16:45:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/03\/IMG_20230308_165038.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veronicapastor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veronicapastor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/\"},\"author\":{\"name\":\"veronicapastor\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/1f45b67e52b27da175190a574db6bed9\"},\"headline\":\"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023\",\"datePublished\":\"2023-03-08T16:45:53+00:00\",\"dateModified\":\"2023-03-08T16:45:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/\"},\"wordCount\":392,\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/IMG_20230308_165038.jpg\",\"articleSection\":[\"Noticia Colegio\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/\",\"name\":\"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023 - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/IMG_20230308_165038.jpg\",\"datePublished\":\"2023-03-08T16:45:53+00:00\",\"dateModified\":\"2023-03-08T16:45:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/1f45b67e52b27da175190a574db6bed9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/IMG_20230308_165038.jpg\",\"contentUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/IMG_20230308_165038.jpg\",\"width\":1080,\"height\":1607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/1f45b67e52b27da175190a574db6bed9\",\"name\":\"veronicapastor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g\",\"caption\":\"veronicapastor\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023 - Colegio San Juan Bosco Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/","og_locale":"es_ES","og_type":"article","og_title":"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023 - Colegio San Juan Bosco Valencia","og_description":"La valoraci\u00f3n de las donaciones realizadas de productos de primera necesidad asciende a 1362,92 euros. Esta es una muestra de ayuda y cari\u00f1o a nuestros hermanos m\u00e1s necesitados en nuestra lucha diaria por un mundo m\u00e1s justo y fraterno. \u00a0Redacci\u00f3n.El colegio quiere sumarse a este agradecimiento a todas las personas que con estos peque\u00f1os actos [&hellip;]","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_published_time":"2023-03-08T16:45:53+00:00","article_modified_time":"2023-03-08T16:45:58+00:00","og_image":[{"width":1080,"height":1607,"url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/03\/IMG_20230308_165038.jpg","type":"image\/jpeg"}],"author":"veronicapastor","twitter_card":"summary_large_image","twitter_creator":"@SalesianosVSJB","twitter_site":"@SalesianosVSJB","twitter_misc":{"Escrito por":"veronicapastor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/#article","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/"},"author":{"name":"veronicapastor","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/1f45b67e52b27da175190a574db6bed9"},"headline":"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023","datePublished":"2023-03-08T16:45:53+00:00","dateModified":"2023-03-08T16:45:58+00:00","mainEntityOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/"},"wordCount":392,"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/03\/IMG_20230308_165038.jpg","articleSection":["Noticia Colegio"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/","name":"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023 - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/#primaryimage"},"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/03\/IMG_20230308_165038.jpg","datePublished":"2023-03-08T16:45:53+00:00","dateModified":"2023-03-08T16:45:58+00:00","author":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/1f45b67e52b27da175190a574db6bed9"},"breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/#primaryimage","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/03\/IMG_20230308_165038.jpg","contentUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/03\/IMG_20230308_165038.jpg","width":1080,"height":1607},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/el-economato-de-caritas-arciprestal-de-la-fonteta-traslada-su-agradecimiento-a-la-comunidad-educativo-pastoral-con-motivo-de-la-colaboracion-en-la-campana-de-navidad-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"El Economato de C\u00e1ritas arciprestal de La Fonteta traslada su agradecimiento a la comunidad educativo-pastoral con motivo de la colaboraci\u00f3n en la campa\u00f1a de Navidad 2023"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/1f45b67e52b27da175190a574db6bed9","name":"veronicapastor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g","caption":"veronicapastor"}}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/18945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=18945"}],"version-history":[{"count":4,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/18945\/revisions"}],"predecessor-version":[{"id":18951,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/18945\/revisions\/18951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/18948"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=18945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=18945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=18945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}