{"id":19421,"date":"2022-06-14T17:14:55","date_gmt":"2022-06-14T16:14:55","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?p=19421"},"modified":"2023-06-26T17:21:55","modified_gmt":"2023-06-26T16:21:55","slug":"nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor","status":"publish","type":"post","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/","title":{"rendered":"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.21.0&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<div id=\"resumen\"><strong>Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole.<\/strong><\/div>\n<div>\u00a0<\/div>\n<div><strong>Nos cuentan que est\u00e1n encantados y aprendiendo muchas cosas interesantes que pronto nos compartir\u00e1n.\u00a0<\/strong><\/div>\n<div>\u00a0<\/div>\n<div>Han aprendido diferentes t\u00e9cnicas para el trabajo por proyectos que est\u00e1n implementando en este centro con mucha experiencia en esta metodolog\u00eda de trabajo.<\/div>\n<div>\u00a0<\/div>\n<div>Est\u00e1 estancia de formaci\u00f3n de job shadowing est\u00e1 teniendo lugar dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND: Metodolog\u00edas para la Atenci\u00f3n en la Diversidad.<\/div>\n<div>\u00a0<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbAutor (Texto)\u00bb _builder_version=\u00bb4.21.0&#8243; text_font=\u00bb||on||\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Redacci\u00f3n Erasmus+<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.21.0&#8243; text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>M\u00e1s informaci\u00f3n:<\/p>\n<p>https:\/\/sites.google.com\/salesianos.edu\/mind<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bboff|on|on\u00bb admin_label=\u00bbT\u00edtulo: Galer\u00eda de fotos (Texto)\u00bb _builder_version=\u00bb4.18.0&#8243; text_font=\u00bb|on|||\u00bb text_text_color=\u00bb#dc001b\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Galer\u00eda de im\u00e1genes<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb19424&#8243; posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#dc001b\u00bb hover_icon=\u00bb&#x54;||divi||400&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.21.0&#8243; hover_enabled=\u00bb0&#8243; pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_gallery][et_pb_video disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole. \u00a0 Nos cuentan que est\u00e1n encantados y aprendiendo muchas cosas interesantes que pronto nos compartir\u00e1n.\u00a0 \u00a0 Han aprendido diferentes t\u00e9cnicas para el trabajo por proyectos que est\u00e1n implementando en este centro con mucha experiencia [&hellip;]<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":19424,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-19421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogerasmus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole. \u00a0 Nos cuentan que est\u00e1n encantados y aprendiendo muchas cosas interesantes que pronto nos compartir\u00e1n.\u00a0 \u00a0 Han aprendido diferentes t\u00e9cnicas para el trabajo por proyectos que est\u00e1n implementando en este centro con mucha experiencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-14T16:14:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T16:21:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/06\/FetnS-6XEAIIbL9-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veronicapastor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veronicapastor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/\"},\"author\":{\"name\":\"veronicapastor\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/1f45b67e52b27da175190a574db6bed9\"},\"headline\":\"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND\",\"datePublished\":\"2022-06-14T16:14:55+00:00\",\"dateModified\":\"2023-06-26T16:21:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/\"},\"wordCount\":428,\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/FetnS-6XEAIIbL9-1.jpeg\",\"articleSection\":[\"Blog Erasmus+\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/\",\"name\":\"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/FetnS-6XEAIIbL9-1.jpeg\",\"datePublished\":\"2022-06-14T16:14:55+00:00\",\"dateModified\":\"2023-06-26T16:21:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/1f45b67e52b27da175190a574db6bed9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/FetnS-6XEAIIbL9-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/FetnS-6XEAIIbL9-1.jpeg\",\"width\":740,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/1f45b67e52b27da175190a574db6bed9\",\"name\":\"veronicapastor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g\",\"caption\":\"veronicapastor\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND - Colegio San Juan Bosco Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/","og_locale":"es_ES","og_type":"article","og_title":"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND - Colegio San Juan Bosco Valencia","og_description":"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole. \u00a0 Nos cuentan que est\u00e1n encantados y aprendiendo muchas cosas interesantes que pronto nos compartir\u00e1n.\u00a0 \u00a0 Han aprendido diferentes t\u00e9cnicas para el trabajo por proyectos que est\u00e1n implementando en este centro con mucha experiencia [&hellip;]","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_published_time":"2022-06-14T16:14:55+00:00","article_modified_time":"2023-06-26T16:21:55+00:00","og_image":[{"width":740,"height":1600,"url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/06\/FetnS-6XEAIIbL9-1.jpeg","type":"image\/jpeg"}],"author":"veronicapastor","twitter_card":"summary_large_image","twitter_creator":"@SalesianosVSJB","twitter_site":"@SalesianosVSJB","twitter_misc":{"Escrito por":"veronicapastor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/#article","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/"},"author":{"name":"veronicapastor","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/1f45b67e52b27da175190a574db6bed9"},"headline":"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND","datePublished":"2022-06-14T16:14:55+00:00","dateModified":"2023-06-26T16:21:55+00:00","mainEntityOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/"},"wordCount":428,"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/06\/FetnS-6XEAIIbL9-1.jpeg","articleSection":["Blog Erasmus+"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/","name":"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/#primaryimage"},"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/06\/FetnS-6XEAIIbL9-1.jpeg","datePublished":"2022-06-14T16:14:55+00:00","dateModified":"2023-06-26T16:21:55+00:00","author":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/1f45b67e52b27da175190a574db6bed9"},"breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/#primaryimage","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/06\/FetnS-6XEAIIbL9-1.jpeg","contentUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/06\/FetnS-6XEAIIbL9-1.jpeg","width":740,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/nuestros-companeros-alvaro-carrasco-de-primaria-y-roman-ribelles-de-secundaria-se-encuentran-de-estancia-en-el-colegio-danes-olgod-skole-dentro-del-programa-erasmus-plus-de-formacion-del-profesor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Nuestros compa\u00f1eros \u00c1lvaro Carrasco, de primaria, y Rom\u00e1n Ribelles, de secundaria, se encuentran de estancia en el colegio dan\u00e9s Olgod Skole, dentro del programa Erasmus Plus de formaci\u00f3n del profesorado MIND"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/1f45b67e52b27da175190a574db6bed9","name":"veronicapastor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e29bd40bace3fd935e1d6fdb7313ffc14628cc037c5e16f4c7369b20a2a6f7f0?s=96&d=mm&r=g","caption":"veronicapastor"}}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/19421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=19421"}],"version-history":[{"count":4,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/19421\/revisions"}],"predecessor-version":[{"id":19427,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/19421\/revisions\/19427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/19424"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=19421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=19421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=19421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}