{"id":22163,"date":"2024-09-26T10:56:39","date_gmt":"2024-09-26T09:56:39","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?p=22163"},"modified":"2024-09-26T10:56:45","modified_gmt":"2024-09-26T09:56:45","slug":"dia-europeo-de-las-lenguas","status":"publish","type":"post","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/","title":{"rendered":"D\u00eda Europeo de las Lenguas"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.27.0&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div id=\"resumen\"><strong>Hoy, d\u00eda 26 de septiembre, celebramos el D\u00eda Europeo de las Lenguas en el Colegio Salesianos San Juan Bosco de Valencia<\/strong><\/div>\n<div>\u00a0<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbAutor (Texto)\u00bb _builder_version=\u00bb4.27.0&#8243; text_font=\u00bb||on||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Equipo internacionalizaci\u00f3n<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.27.0&#8243; text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Querida comunidad educativa, hoy es un d\u00eda muy especial: <strong>\u00a1el D\u00eda Europeo de las Lenguas!<\/strong> Un momento para reconocer y valorar la riqueza que cada lengua aporta al mundo. Aqu\u00ed, en Salesianos San Juan Bosco de Valencia, nos enorgullece formar parte de esta celebraci\u00f3n, conscientes de que las lenguas no son solo herramientas de comunicaci\u00f3n, sino verdaderos tesoros que preservan la historia, el arte y el sentir profundo de los pueblos.<\/p>\n<p>En este curso, con nuestro lema <strong>SOMOS FUTURO<\/strong>, entendemos que cada lengua que aprendemos nos prepara mejor para el ma\u00f1ana. Nos abre horizontes, nos invita a conocer y respetar otras culturas, y nos impulsa a construir un mundo m\u00e1s unido y solidario. Porque en cada idioma que exploramos, estamos tambi\u00e9n cultivando el futuro que so\u00f1amos: uno donde las barreras se superan y donde la diversidad es nuestra fortaleza.<\/p>\n<p>Como colegio cristiano, creemos que las lenguas tambi\u00e9n nos ayudan a seguir el mensaje de amor y fraternidad de Jes\u00fas. Cada palabra que aprendemos es una oportunidad para tender puentes, vivir la solidaridad y llevar el Evangelio a todas las naciones. Valoramos y respetamos las lenguas porque, como hijos de Dios, estamos llamados a construir un mundo m\u00e1s justo y en comuni\u00f3n, donde la cultura y el lenguaje de cada persona sean un reflejo de su dignidad.<\/p>\n<p>As\u00ed que hoy, al celebrar esta jornada, recordemos que SOMOS FUTURO. El futuro que juntos construimos, lleno de diversidad, respeto y amor cristiano.<\/p>\n<p><strong>\u00a1Feliz D\u00eda Europeo de las Lenguas!\u00bb<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p dir=\"ltr\">#ErasmusPlus<\/p>\n<p dir=\"ltr\">@Servicio espa\u00f1ol para la internacionalizaci\u00f3n de la educaci\u00f3n<\/p>\n<p dir=\"ltr\">@sepie_gob<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbT\u00edtulo: Galer\u00eda de fotos (Texto)\u00bb _builder_version=\u00bb4.27.0&#8243; text_font=\u00bb|on|||\u00bb text_text_color=\u00bb#dc001b\u00bb hover_enabled=\u00bb0&#8243; border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Galer\u00eda de im\u00e1genes<\/p>\n<p>[\/et_pb_text][et_pb_gallery posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#dc001b\u00bb hover_icon=\u00bb&#x54;||divi||400&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.0&#8243; hover_enabled=\u00bb0&#8243; pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; global_colors_info=\u00bb{}\u00bb gallery_ids=\u00bb22167,22168,22169,22170,22171,22172,22173,22174&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_gallery][et_pb_video disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy, d\u00eda 26 de septiembre, celebramos el D\u00eda Europeo de las Lenguas en el Colegio Salesianos San Juan Bosco de Valencia \u00a0Equipo internacionalizaci\u00f3nQuerida comunidad educativa, hoy es un d\u00eda muy especial: \u00a1el D\u00eda Europeo de las Lenguas! Un momento para reconocer y valorar la riqueza que cada lengua aporta al mundo. Aqu\u00ed, en Salesianos San [&hellip;]<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":22176,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[42,14,1],"tags":[],"class_list":["post-22163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogerasmus","category-noticia_colegio","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Europeo de las Lenguas - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Europeo de las Lenguas - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"Hoy, d\u00eda 26 de septiembre, celebramos el D\u00eda Europeo de las Lenguas en el Colegio Salesianos San Juan Bosco de Valencia \u00a0Equipo internacionalizaci\u00f3nQuerida comunidad educativa, hoy es un d\u00eda muy especial: \u00a1el D\u00eda Europeo de las Lenguas! Un momento para reconocer y valorar la riqueza que cada lengua aporta al mundo. Aqu\u00ed, en Salesianos San [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-26T09:56:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T09:56:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/09\/IMG_3097.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/\"},\"author\":{\"name\":\"Administrador Web\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\"},\"headline\":\"D\u00eda Europeo de las Lenguas\",\"datePublished\":\"2024-09-26T09:56:39+00:00\",\"dateModified\":\"2024-09-26T09:56:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/\"},\"wordCount\":537,\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/09\\\/IMG_3097.jpg\",\"articleSection\":[\"Blog Erasmus+\",\"Noticia Colegio\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/\",\"name\":\"D\u00eda Europeo de las Lenguas - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/09\\\/IMG_3097.jpg\",\"datePublished\":\"2024-09-26T09:56:39+00:00\",\"dateModified\":\"2024-09-26T09:56:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/09\\\/IMG_3097.jpg\",\"contentUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/09\\\/IMG_3097.jpg\",\"width\":1500,\"height\":1181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Europeo de las Lenguas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\",\"name\":\"Administrador Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"caption\":\"Administrador Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Europeo de las Lenguas - Colegio San Juan Bosco Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda Europeo de las Lenguas - Colegio San Juan Bosco Valencia","og_description":"Hoy, d\u00eda 26 de septiembre, celebramos el D\u00eda Europeo de las Lenguas en el Colegio Salesianos San Juan Bosco de Valencia \u00a0Equipo internacionalizaci\u00f3nQuerida comunidad educativa, hoy es un d\u00eda muy especial: \u00a1el D\u00eda Europeo de las Lenguas! Un momento para reconocer y valorar la riqueza que cada lengua aporta al mundo. Aqu\u00ed, en Salesianos San [&hellip;]","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_published_time":"2024-09-26T09:56:39+00:00","article_modified_time":"2024-09-26T09:56:45+00:00","og_image":[{"width":1500,"height":1181,"url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/09\/IMG_3097.jpg","type":"image\/jpeg"}],"author":"Administrador Web","twitter_card":"summary_large_image","twitter_creator":"@SalesianosVSJB","twitter_site":"@SalesianosVSJB","twitter_misc":{"Escrito por":"Administrador Web","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/#article","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/"},"author":{"name":"Administrador Web","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575"},"headline":"D\u00eda Europeo de las Lenguas","datePublished":"2024-09-26T09:56:39+00:00","dateModified":"2024-09-26T09:56:45+00:00","mainEntityOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/"},"wordCount":537,"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/09\/IMG_3097.jpg","articleSection":["Blog Erasmus+","Noticia Colegio","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/","name":"D\u00eda Europeo de las Lenguas - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/#primaryimage"},"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/09\/IMG_3097.jpg","datePublished":"2024-09-26T09:56:39+00:00","dateModified":"2024-09-26T09:56:45+00:00","author":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575"},"breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/#primaryimage","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/09\/IMG_3097.jpg","contentUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/09\/IMG_3097.jpg","width":1500,"height":1181},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Europeo de las Lenguas"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575","name":"Administrador Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","caption":"Administrador Web"}}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/22163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=22163"}],"version-history":[{"count":3,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/22163\/revisions"}],"predecessor-version":[{"id":22177,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/22163\/revisions\/22177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/22176"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=22163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=22163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=22163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}