{"id":22342,"date":"2024-10-18T08:09:27","date_gmt":"2024-10-18T07:09:27","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?p=22342"},"modified":"2024-10-18T08:09:34","modified_gmt":"2024-10-18T07:09:34","slug":"erasmus-days","status":"publish","type":"post","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/","title":{"rendered":"Erasmus Days"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.27.2&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div id=\"resumen\">\n<p><strong>\u00a1Celebramos los Erasmus Days 2024 en Salesianos San Juan Bosco!<\/strong><\/p>\n<\/div>\n<div>\u00a0<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbAutor (Texto)\u00bb _builder_version=\u00bb4.27.2&#8243; text_font=\u00bb||on||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Equipo Internacionalizaci\u00f3n<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.27.2&#8243; text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Durante esta semana, en el Colegio Salesianos San Juan Bosco de Valencia, estamos celebrando los\u00a0<em>Erasmus Days 2024<\/em>, una iniciativa internacional dedicada a promover el programa Erasmus+, que se lleva a cabo del 14 al 19 de octubre. Este evento re\u00fane a personas de todo el mundo para participar en actividades que destacan los proyectos y las oportunidades que este programa ofrece a estudiantes, profesores, formadores y ciudadanos en general. Es un momento especial para promover los m\u00faltiples beneficios del programa Erasmus+, y nuestro colegio no pod\u00eda quedarse atr\u00e1s.<\/p>\n<p>El colegio Salesianos San Juan Bosco cuenta con una amplia trayectoria en proyectos Erasmus, cofinanciados por la Uni\u00f3n Europea, que nos han permitido realizar intercambios y colaboraciones con varios pa\u00edses europeos. Gracias a estos proyectos, tanto estudiantes como docentes han tenido la oportunidad de viajar y aprender de otras culturas y sistemas educativos. Este curso seguimos adelante con el proyecto\u00a0<em>3E+<\/em>, que se enfoca en tres \u00e1reas clave: Ecolog\u00eda, Perspectiva Eco-social y Destreza Electr\u00f3nica. Estudiantes desde 6\u00ba de primaria hasta Bachillerato podr\u00e1n participar en movilidades hacia pa\u00edses como Eslovenia, Francia (Lyon) y Alemania (Bocholt).<\/p>\n<p><strong>Actividades especiales en Salesianos San Juan Bosco<\/strong><\/p>\n<p>Para conmemorar esta celebraci\u00f3n, hemos organizado dos actividades especiales:<\/p>\n<ol>\n<li><strong>Our Erasmus Map<\/strong>: En la entrada del colegio, hemos colocado un gran mapa que muestra todos los pa\u00edses que hemos visitado gracias a las becas Erasmus. Tanto alumnos como profesores han dejado huella salesiana en muchos rincones de Europa, y este mapa es un testimonio de los lazos que hemos formado. \u00a1No te lo pierdas!<\/li>\n<li><strong>Programa de Radio Erasmus+<\/strong>: A trav\u00e9s de\u00a0<em>Radio Bosco<\/em>, hemos compartido las vivencias de docentes y estudiantes, quienes hablan de c\u00f3mo el programa Erasmus+ ha enriquecido sus vidas. Las experiencias compartidas en este programa reflejan el impacto positivo que Erasmus+ tiene en nuestra comunidad educativa, promoviendo la apertura cultural, el aprendizaje de idiomas y el desarrollo de habilidades para la vida. Sintoniza Radio Bosco para escuchar estas historias inspiradoras.<\/li>\n<\/ol>\n<p>El programa Erasmus+ no solo fomenta el aprendizaje acad\u00e9mico, sino que tambi\u00e9n nos abre al mundo, nos ayuda a descubrir nuevas culturas y valores, y nos permite desarrollar habilidades que nos acompa\u00f1ar\u00e1n toda la vida. Todo esto est\u00e1 en perfecta sinton\u00eda con los ideales salesianos, que buscan la solidaridad, la educaci\u00f3n integral y la fraternidad entre los pueblos.<\/p>\n<p>Te invitamos a seguir la web y las redes sociales del colegio para no perderte nada. \u00a1Participa y s\u00e9 parte de esta gran familia Erasmus+!<\/p>\n<p><strong>\u00a1Erasmus+, experiencias que te cambian la vida!<\/strong><\/p>\n<p dir=\"ltr\">#ErasmusPlus<\/p>\n<p dir=\"ltr\">@Servicio espa\u00f1ol para la internacionalizaci\u00f3n de la educaci\u00f3n<\/p>\n<p dir=\"ltr\">@sepiegob<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbT\u00edtulo: Galer\u00eda de fotos (Texto)\u00bb _builder_version=\u00bb4.27.0&#8243; text_font=\u00bb|on|||\u00bb text_text_color=\u00bb#dc001b\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Galer\u00eda de im\u00e1genes<\/p>\n<p>[\/et_pb_text][et_pb_gallery posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#dc001b\u00bb hover_icon=\u00bb&#x54;||divi||400&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.2&#8243; hover_enabled=\u00bb0&#8243; pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; global_colors_info=\u00bb{}\u00bb gallery_ids=\u00bb22348,22350&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_gallery][et_pb_video disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00a1Celebramos los Erasmus Days 2024 en Salesianos San Juan Bosco! \u00a0Equipo Internacionalizaci\u00f3nDurante esta semana, en el Colegio Salesianos San Juan Bosco de Valencia, estamos celebrando los\u00a0Erasmus Days 2024, una iniciativa internacional dedicada a promover el programa Erasmus+, que se lleva a cabo del 14 al 19 de octubre. Este evento re\u00fane a personas de todo [&hellip;]<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":22348,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[42,14,1],"tags":[],"class_list":["post-22342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogerasmus","category-noticia_colegio","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erasmus Days - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erasmus Days - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"\u00a1Celebramos los Erasmus Days 2024 en Salesianos San Juan Bosco! \u00a0Equipo Internacionalizaci\u00f3nDurante esta semana, en el Colegio Salesianos San Juan Bosco de Valencia, estamos celebrando los\u00a0Erasmus Days 2024, una iniciativa internacional dedicada a promover el programa Erasmus+, que se lleva a cabo del 14 al 19 de octubre. Este evento re\u00fane a personas de todo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-18T07:09:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-18T07:09:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/10\/unnamed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"644\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/\"},\"author\":{\"name\":\"Administrador Web\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\"},\"headline\":\"Erasmus Days\",\"datePublished\":\"2024-10-18T07:09:27+00:00\",\"dateModified\":\"2024-10-18T07:09:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/\"},\"wordCount\":681,\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/10\\\/unnamed.jpg\",\"articleSection\":[\"Blog Erasmus+\",\"Noticia Colegio\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/\",\"name\":\"Erasmus Days - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/10\\\/unnamed.jpg\",\"datePublished\":\"2024-10-18T07:09:27+00:00\",\"dateModified\":\"2024-10-18T07:09:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/10\\\/unnamed.jpg\",\"contentUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/10\\\/unnamed.jpg\",\"width\":1000,\"height\":644},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erasmus Days\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\",\"name\":\"Administrador Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"caption\":\"Administrador Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erasmus Days - Colegio San Juan Bosco Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/","og_locale":"es_ES","og_type":"article","og_title":"Erasmus Days - Colegio San Juan Bosco Valencia","og_description":"\u00a1Celebramos los Erasmus Days 2024 en Salesianos San Juan Bosco! \u00a0Equipo Internacionalizaci\u00f3nDurante esta semana, en el Colegio Salesianos San Juan Bosco de Valencia, estamos celebrando los\u00a0Erasmus Days 2024, una iniciativa internacional dedicada a promover el programa Erasmus+, que se lleva a cabo del 14 al 19 de octubre. Este evento re\u00fane a personas de todo [&hellip;]","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_published_time":"2024-10-18T07:09:27+00:00","article_modified_time":"2024-10-18T07:09:34+00:00","og_image":[{"width":1000,"height":644,"url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/10\/unnamed.jpg","type":"image\/jpeg"}],"author":"Administrador Web","twitter_card":"summary_large_image","twitter_creator":"@SalesianosVSJB","twitter_site":"@SalesianosVSJB","twitter_misc":{"Escrito por":"Administrador Web","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/#article","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/"},"author":{"name":"Administrador Web","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575"},"headline":"Erasmus Days","datePublished":"2024-10-18T07:09:27+00:00","dateModified":"2024-10-18T07:09:34+00:00","mainEntityOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/"},"wordCount":681,"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/10\/unnamed.jpg","articleSection":["Blog Erasmus+","Noticia Colegio","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/","name":"Erasmus Days - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/#primaryimage"},"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/10\/unnamed.jpg","datePublished":"2024-10-18T07:09:27+00:00","dateModified":"2024-10-18T07:09:34+00:00","author":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575"},"breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/#primaryimage","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/10\/unnamed.jpg","contentUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/10\/unnamed.jpg","width":1000,"height":644},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Erasmus Days"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575","name":"Administrador Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","caption":"Administrador Web"}}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/22342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=22342"}],"version-history":[{"count":4,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/22342\/revisions"}],"predecessor-version":[{"id":22351,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/22342\/revisions\/22351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/22348"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=22342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=22342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=22342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}