{"id":23872,"date":"2025-09-30T10:53:33","date_gmt":"2025-09-30T09:53:33","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?p=23872"},"modified":"2025-09-30T11:10:34","modified_gmt":"2025-09-30T10:10:34","slug":"dia-europeo-de-las-lenguas-2025","status":"publish","type":"post","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/","title":{"rendered":"D\u00eda Europeo de las Lenguas 2025"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.27.4&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><b><span style=\"font-size: large;\" data-removefontsize=\"true\" data-originalcomputedfontsize=\"18\">Lenguas que unen, diversidad que nos hace protagonistas de la historia<\/span><\/b><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbAutor (Texto)\u00bb _builder_version=\u00bb4.27.0&#8243; text_font=\u00bb||on||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Equipo internacionalizaci\u00f3n<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.27.4&#8243; text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">El pasado 26 de septiembre, nuestro centro conmemor\u00f3 el D\u00eda Europeo de las Lenguas, una jornada instaurada por el Consejo de Europa en 2001 con el objetivo de promover la diversidad ling\u00fc\u00edstica, el aprendizaje de idiomas y la comunicaci\u00f3n intercultural.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Durante la semana, el alumnado pudo conocer mejor el sentido de esta celebraci\u00f3n a trav\u00e9s de los discursos de los Buenos D\u00edas, en los que se subray\u00f3 la importancia de las lenguas como puentes que unen culturas, favorecen la convivencia y ayudan a construir la paz.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Como parte central de la jornada, todas las etapas educativas colaboraron en la creaci\u00f3n de un mural colectivo. En \u00e9l, nuestro alumnado plasm\u00f3 palabras, s\u00edmbolos, frases y dichos en favor de la paz y la uni\u00f3n, escritos en las distintas lenguas que forman parte de nuestra comunidad educativa.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Adem\u00e1s, y con la implicaci\u00f3n de todo el centro, se grab\u00f3 un videoclip conmemorativo en el que se unen m\u00fasica, im\u00e1genes y mensajes multiling\u00fces, con un mismo prop\u00f3sito: celebrar la diversidad cultural y ling\u00fc\u00edstica, y hacer un llamamiento por la paz y la convivencia.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">Este d\u00eda nos recuerda que las lenguas no nos dividen, sino que nos unen, y que la diversidad es una riqueza que nos convierte en protagonistas de la historia.<\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\"><a href=\"https:\/\/www.instagram.com\/reel\/DPDsiHDiFRn\/?igsh=MXZ4N2R6Nmxlcmhmag==\">Video en Instagram<\/a><\/p>\n<p data-removefontsize=\"true\" data-originalcomputedfontsize=\"16\">#ErasmusPlus<\/p>\n<p dir=\"ltr\">@Servicio espa\u00f1ol para la internacionalizaci\u00f3n de la educaci\u00f3n<\/p>\n<p dir=\"ltr\">@sepie_gob<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbT\u00edtulo: Galer\u00eda de fotos (Texto)\u00bb _builder_version=\u00bb4.27.0&#8243; text_font=\u00bb|on|||\u00bb text_text_color=\u00bb#dc001b\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Galer\u00eda de im\u00e1genes<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb23883,23884,23885,23886,23887,23888,23889,23890,23891,23892,23893,23894,23895,23896,23897,23898,23899,23900,23901,23902,23903,23904,23905,23906,23907,23908,23909,23910,23911,23912,23913,23914,23915,23916,23917,23918,23919,23920,23921,23922,23923,23924,23925,23926,23927,23928,23929,23930,23931,23932,23933,23934,23935,23936,23937,23938,23939,23940,23941,23942,23943,23944,23945&#8243; posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#dc001b\u00bb hover_icon=\u00bb&#x54;||divi||400&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.4&#8243; pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][et_pb_video disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Lenguas que unen, diversidad que nos hace protagonistas de la historiaEquipo internacionalizaci\u00f3nEl pasado 26 de septiembre, nuestro centro conmemor\u00f3 el D\u00eda Europeo de las Lenguas, una jornada instaurada por el Consejo de Europa en 2001 con el objetivo de promover la diversidad ling\u00fc\u00edstica, el aprendizaje de idiomas y la comunicaci\u00f3n intercultural. Durante la semana, el [&hellip;]<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":23880,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[42,14,1],"tags":[],"class_list":["post-23872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogerasmus","category-noticia_colegio","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Europeo de las Lenguas 2025 - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Europeo de las Lenguas 2025 - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"Lenguas que unen, diversidad que nos hace protagonistas de la historiaEquipo internacionalizaci\u00f3nEl pasado 26 de septiembre, nuestro centro conmemor\u00f3 el D\u00eda Europeo de las Lenguas, una jornada instaurada por el Consejo de Europa en 2001 con el objetivo de promover la diversidad ling\u00fc\u00edstica, el aprendizaje de idiomas y la comunicaci\u00f3n intercultural. Durante la semana, el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T09:53:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T10:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_6820.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"795\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Administrador Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/\"},\"author\":{\"name\":\"Administrador Web\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\"},\"headline\":\"D\u00eda Europeo de las Lenguas 2025\",\"datePublished\":\"2025-09-30T09:53:33+00:00\",\"dateModified\":\"2025-09-30T10:10:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/\"},\"wordCount\":484,\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/IMG_6820.png\",\"articleSection\":[\"Blog Erasmus+\",\"Noticia Colegio\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/\",\"name\":\"D\u00eda Europeo de las Lenguas 2025 - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/IMG_6820.png\",\"datePublished\":\"2025-09-30T09:53:33+00:00\",\"dateModified\":\"2025-09-30T10:10:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/IMG_6820.png\",\"contentUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/09\\\/IMG_6820.png\",\"width\":1000,\"height\":795},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/dia-europeo-de-las-lenguas-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Europeo de las Lenguas 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\",\"name\":\"Administrador Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"caption\":\"Administrador Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Europeo de las Lenguas 2025 - Colegio San Juan Bosco Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda Europeo de las Lenguas 2025 - Colegio San Juan Bosco Valencia","og_description":"Lenguas que unen, diversidad que nos hace protagonistas de la historiaEquipo internacionalizaci\u00f3nEl pasado 26 de septiembre, nuestro centro conmemor\u00f3 el D\u00eda Europeo de las Lenguas, una jornada instaurada por el Consejo de Europa en 2001 con el objetivo de promover la diversidad ling\u00fc\u00edstica, el aprendizaje de idiomas y la comunicaci\u00f3n intercultural. Durante la semana, el [&hellip;]","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_published_time":"2025-09-30T09:53:33+00:00","article_modified_time":"2025-09-30T10:10:34+00:00","og_image":[{"width":1000,"height":795,"url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_6820.png","type":"image\/png"}],"author":"Administrador Web","twitter_card":"summary_large_image","twitter_creator":"@SalesianosVSJB","twitter_site":"@SalesianosVSJB","twitter_misc":{"Escrito por":"Administrador Web","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/#article","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/"},"author":{"name":"Administrador Web","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575"},"headline":"D\u00eda Europeo de las Lenguas 2025","datePublished":"2025-09-30T09:53:33+00:00","dateModified":"2025-09-30T10:10:34+00:00","mainEntityOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/"},"wordCount":484,"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_6820.png","articleSection":["Blog Erasmus+","Noticia Colegio","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/","name":"D\u00eda Europeo de las Lenguas 2025 - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/#primaryimage"},"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_6820.png","datePublished":"2025-09-30T09:53:33+00:00","dateModified":"2025-09-30T10:10:34+00:00","author":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575"},"breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/#primaryimage","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_6820.png","contentUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/09\/IMG_6820.png","width":1000,"height":795},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/dia-europeo-de-las-lenguas-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Europeo de las Lenguas 2025"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575","name":"Administrador Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","caption":"Administrador Web"}}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/23872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=23872"}],"version-history":[{"count":8,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/23872\/revisions"}],"predecessor-version":[{"id":23947,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/23872\/revisions\/23947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/23880"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=23872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=23872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=23872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}