{"id":23983,"date":"2025-10-15T08:23:51","date_gmt":"2025-10-15T07:23:51","guid":{"rendered":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?p=23983"},"modified":"2025-10-15T08:24:13","modified_gmt":"2025-10-15T07:24:13","slug":"erasmus-days-2","status":"publish","type":"post","link":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/","title":{"rendered":"Erasmus days"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb4.27.4&#8243; text_font=\u00bb|on|||\u00bb text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<b>\u00a0\u00a1Comenzaron ayer los #ErasmusDays 2025 en nuestro centro!<\/b><br \/>\n[\/et_pb_text][et_pb_text admin_label=\u00bbAutor (Texto)\u00bb _builder_version=\u00bb4.27.0&#8243; text_font=\u00bb||on||\u00bb global_colors_info=\u00bb{}\u00bb]Equipo internacionalizaci\u00f3n<br \/>\n[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb4.27.4&#8243; text_orientation=\u00bbjustified\u00bb module_alignment=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]Ayer dimos inicio a la celebraci\u00f3n de los\u00a0Erasmus Days 2025\u00a0con un acto muy especial: la imposici\u00f3n de la placa acreditativa que nos reconoce oficialmente como\u00a0Centro Acreditado Erasmus+.<\/p>\n<p>Este distintivo refleja el compromiso de toda la comunidad educativa con los valores europeos de inclusi\u00f3n, cooperaci\u00f3n, sostenibilidad y apertura al mundo. Gracias a esta acreditaci\u00f3n, nuestro alumnado y profesorado seguir\u00e1n participando en proyectos y movilidades internacionales que fomentan el aprendizaje global y la ciudadan\u00eda europea.<\/p>\n<p>Durante toda la semana, disfrutaremos de distintas actividades para celebrar nuestra trayectoria y el esp\u00edritu Erasmus:<br \/>\nExposici\u00f3n de un\u00a0mural conmemorativo\u00a0de nuestro recorrido europeo.<br \/>\nPrograma de radio \u201cOndas Erasmus: Conectando Culturas desde Nuestro Centro\u201d, donde compartiremos experiencias y entrevistas.<br \/>\nEl mi\u00e9rcoles a las 17:30h:\u00a0Reuni\u00f3n de Puertas Abiertas Erasmus+, en la que presentaremos nuestro Plan de Internacionalizaci\u00f3n y Plan Erasmus 2024-2027.<br \/>\nLanzamiento del\u00a0Concurso de Logos, para elegir la imagen que representar\u00e1 a nuestro proyecto y al centro como acreditado Erasmus+.<\/p>\n<p>\u00a1Sigue nuestras redes sociales para no perderte nada de esta semana llena de cooperaci\u00f3n, cultura y aprendizaje europeo!<br \/>\n#ErasmusDays #ErasmusPlus\u00a0 #ErasmusAccredited #centroacreditado<br \/>\n[\/et_pb_text][et_pb_text disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbT\u00edtulo: Galer\u00eda de fotos (Texto)\u00bb _builder_version=\u00bb4.27.0&#8243; text_font=\u00bb|on|||\u00bb text_text_color=\u00bb#dc001b\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]Galer\u00eda de im\u00e1genes<br \/>\n[\/et_pb_text][et_pb_gallery gallery_ids=\u00bb23991,23992,23986&#8243; posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#dc001b\u00bb hover_icon=\u00bb&#x54;||divi||400&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.4&#8243; pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][et_pb_video disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a1Comenzaron ayer los #ErasmusDays 2025 en nuestro centro! Equipo internacionalizaci\u00f3n Ayer dimos inicio a la celebraci\u00f3n de los\u00a0Erasmus Days 2025\u00a0con un acto muy especial: la imposici\u00f3n de la placa acreditativa que nos reconoce oficialmente como\u00a0Centro Acreditado Erasmus+. Este distintivo refleja el compromiso de toda la comunidad educativa con los valores europeos de inclusi\u00f3n, cooperaci\u00f3n, sostenibilidad [&hellip;]<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":23986,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[42,14,1],"tags":[],"class_list":["post-23983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogerasmus","category-noticia_colegio","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erasmus days - Colegio San Juan Bosco Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erasmus days - Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"og:description\" content=\"\u00a0\u00a1Comenzaron ayer los #ErasmusDays 2025 en nuestro centro! Equipo internacionalizaci\u00f3n Ayer dimos inicio a la celebraci\u00f3n de los\u00a0Erasmus Days 2025\u00a0con un acto muy especial: la imposici\u00f3n de la placa acreditativa que nos reconoce oficialmente como\u00a0Centro Acreditado Erasmus+. Este distintivo refleja el compromiso de toda la comunidad educativa con los valores europeos de inclusi\u00f3n, cooperaci\u00f3n, sostenibilidad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio San Juan Bosco Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T07:23:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T07:24:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/10\/erasmus-days-03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2009\" \/>\n\t<meta property=\"og:image:height\" content=\"1542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:site\" content=\"@SalesianosVSJB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/\"},\"author\":{\"name\":\"Administrador Web\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\"},\"headline\":\"Erasmus days\",\"datePublished\":\"2025-10-15T07:23:51+00:00\",\"dateModified\":\"2025-10-15T07:24:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/\"},\"wordCount\":425,\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/erasmus-days-03.jpg\",\"articleSection\":[\"Blog Erasmus+\",\"Noticia Colegio\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/\",\"name\":\"Erasmus days - Colegio San Juan Bosco Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/erasmus-days-03.jpg\",\"datePublished\":\"2025-10-15T07:23:51+00:00\",\"dateModified\":\"2025-10-15T07:24:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/erasmus-days-03.jpg\",\"contentUrl\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/erasmus-days-03.jpg\",\"width\":2009,\"height\":1542},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/erasmus-days-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erasmus days\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio San Juan Bosco Valencia\",\"description\":\"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia\",\"alternateName\":\"Salesianos.VSJB\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/valenciasjb.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/ae0ac91eb19a6a2a01c95e29d541a575\",\"name\":\"Administrador Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g\",\"caption\":\"Administrador Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erasmus days - Colegio San Juan Bosco Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/","og_locale":"es_ES","og_type":"article","og_title":"Erasmus days - Colegio San Juan Bosco Valencia","og_description":"\u00a0\u00a1Comenzaron ayer los #ErasmusDays 2025 en nuestro centro! Equipo internacionalizaci\u00f3n Ayer dimos inicio a la celebraci\u00f3n de los\u00a0Erasmus Days 2025\u00a0con un acto muy especial: la imposici\u00f3n de la placa acreditativa que nos reconoce oficialmente como\u00a0Centro Acreditado Erasmus+. Este distintivo refleja el compromiso de toda la comunidad educativa con los valores europeos de inclusi\u00f3n, cooperaci\u00f3n, sostenibilidad [&hellip;]","og_url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/","og_site_name":"Colegio San Juan Bosco Valencia","article_publisher":"https:\/\/www.facebook.com\/ColegioSalesianoSanJuanBoscoValencia","article_published_time":"2025-10-15T07:23:51+00:00","article_modified_time":"2025-10-15T07:24:13+00:00","og_image":[{"width":2009,"height":1542,"url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/10\/erasmus-days-03.jpg","type":"image\/jpeg"}],"author":"Administrador Web","twitter_card":"summary_large_image","twitter_creator":"@SalesianosVSJB","twitter_site":"@SalesianosVSJB","twitter_misc":{"Escrito por":"Administrador Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/#article","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/"},"author":{"name":"Administrador Web","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575"},"headline":"Erasmus days","datePublished":"2025-10-15T07:23:51+00:00","dateModified":"2025-10-15T07:24:13+00:00","mainEntityOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/"},"wordCount":425,"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/10\/erasmus-days-03.jpg","articleSection":["Blog Erasmus+","Noticia Colegio","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/","name":"Erasmus days - Colegio San Juan Bosco Valencia","isPartOf":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/#primaryimage"},"image":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/10\/erasmus-days-03.jpg","datePublished":"2025-10-15T07:23:51+00:00","dateModified":"2025-10-15T07:24:13+00:00","author":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575"},"breadcrumb":{"@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/#primaryimage","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/10\/erasmus-days-03.jpg","contentUrl":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/10\/erasmus-days-03.jpg","width":2009,"height":1542},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/erasmus-days-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasjb.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Erasmus days"}]},{"@type":"WebSite","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#website","url":"https:\/\/valenciasjb.salesianos.edu\/colegio\/","name":"Colegio San Juan Bosco Valencia","description":"P\u00e1gina oficial del Colegio Salesianos San Juan Bosco Valencia","alternateName":"Salesianos.VSJB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasjb.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/valenciasjb.salesianos.edu\/colegio\/#\/schema\/person\/ae0ac91eb19a6a2a01c95e29d541a575","name":"Administrador Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a73c544c48a92e9f82115ddc8f6abf90891f033d83384ebe4aafd70f983ec8?s=96&d=mm&r=g","caption":"Administrador Web"}}]}},"_links":{"self":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/23983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=23983"}],"version-history":[{"count":8,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/23983\/revisions"}],"predecessor-version":[{"id":23996,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/23983\/revisions\/23996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/23986"}],"wp:attachment":[{"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=23983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=23983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=23983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}